{"id":5856,"date":"2021-11-02T09:55:04","date_gmt":"2021-11-02T12:55:04","guid":{"rendered":"https:\/\/debitia.com.ar\/?p=5856"},"modified":"2023-05-02T10:14:17","modified_gmt":"2023-05-02T13:14:17","slug":"cuentas-por-cobrar","status":"publish","type":"post","link":"https:\/\/debitia.com\/es_us\/cuentas-por-cobrar\/","title":{"rendered":"Cuentas por Cobrar"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/debitia.com\/es_us\/cuentas-por-cobrar\/#Cuentas_por_Cobrar\" >Cuentas por Cobrar<\/a><ul class='ez-toc-list-level-2' ><li class='ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/debitia.com\/es_us\/cuentas-por-cobrar\/#%C2%BFCuentas_por_cobrar_que_es\" >\u00bfCuentas por cobrar, que es?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/debitia.com\/es_us\/cuentas-por-cobrar\/#%C2%BFComo_hacer_una_buena_gestion_de_cuentas_por_cobrar_%E2%80%93_Medir_el_proceso_de_gestion\" >\u00bfComo hacer una buena gesti\u00f3n de cuentas por cobrar? &#8211; Medir el\u00a0 proceso de gesti\u00f3n.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/debitia.com\/es_us\/cuentas-por-cobrar\/#Definicion_de_la_Gestion_de_cuentas_por_cobrar_%E2%80%93_%C2%BFQue_son_las_cuentas_por_cobrar\" >Definici\u00f3n de la Gesti\u00f3n de cuentas por cobrar \u2013 \u00bfQue son las cuentas por cobrar?:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/debitia.com\/es_us\/cuentas-por-cobrar\/#Como_debemos_gestionar_las_cuentas_por_cobrar\" >Como debemos gestionar las cuentas por cobrar:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/debitia.com\/es_us\/cuentas-por-cobrar\/#%C2%BFQue_hemos_visto_en_distintos_clientes\" >\u00bfQue hemos visto en distintos clientes?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/debitia.com\/es_us\/cuentas-por-cobrar\/#_%C2%BFComo_hacer_una_buena_gestion_de_cuentas_por_cobrar\" >\u00a0\u00bfComo hacer una buena gesti\u00f3n de cuentas por cobrar?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/debitia.com\/es_us\/cuentas-por-cobrar\/#Coordinacion\" >Coordinaci\u00f3n:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/debitia.com\/es_us\/cuentas-por-cobrar\/#%C2%BFComo_dar_soporte_a_la_Gestion_de_cuentas_por_cobrar\" >\u00bfComo dar soporte a la Gesti\u00f3n de cuentas por cobrar?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/debitia.com\/es_us\/cuentas-por-cobrar\/#%C2%BFComo_organizar_las_Cuentas_por_Cobrar_%E2%80%93_%C2%BFCuales_son_los_metodos_de_cobranza\" >\u00bfComo organizar las Cuentas por Cobrar? \u2013 \u00bfCuales son los m\u00e9todos de cobranza?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/debitia.com\/es_us\/cuentas-por-cobrar\/#Workflow_de_Gestion_de_Cobro_Omnicanal\" >Workflow de Gesti\u00f3n de Cobro Omnicanal<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/debitia.com\/es_us\/cuentas-por-cobrar\/#%C2%BFAun_realiza_la_Gestion_de_cuentas_por_cobrar_con_Excel\" >\u00bfA\u00fan realiza\u00a0 la Gesti\u00f3n de cuentas por cobrar con Excel?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/debitia.com\/es_us\/cuentas-por-cobrar\/#Utilice_un_programa_que_permita_la_Gestion_de_cuentas_por_cobrar_con_excel\" >Utilice un programa que permita la Gesti\u00f3n de cuentas por cobrar con excel:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/debitia.com\/es_us\/cuentas-por-cobrar\/#NUESTRA_PROPUESTA\" >NUESTRA PROPUESTA:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/debitia.com\/es_us\/cuentas-por-cobrar\/#Tiene_consultas_queremos_saber_si_tambien_podemos_ayudarloa_haga_Click_en_la_foto_y_charlamos\" >Tiene consultas, queremos saber si tambi\u00e9n podemos ayudarlo\/a haga Click en la foto y charlamos !<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h1><span class=\"ez-toc-section\" id=\"Cuentas_por_Cobrar\"><\/span>Cuentas por Cobrar<span class=\"ez-toc-section-end\"><\/span><\/h1>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3237 size-full\" title=\"cuentas por cobrar\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2018\/09\/Persiguiendo-el-dinero.png\" alt=\"cuentas por cobrar\" width=\"885\" height=\"516\" srcset=\"https:\/\/debitia.com\/wp-content\/uploads\/2018\/09\/Persiguiendo-el-dinero.png 885w, https:\/\/debitia.com\/wp-content\/uploads\/2018\/09\/Persiguiendo-el-dinero-300x175.png 300w, https:\/\/debitia.com\/wp-content\/uploads\/2018\/09\/Persiguiendo-el-dinero-768x448.png 768w\" sizes=\"auto, (max-width: 885px) 100vw, 885px\" \/><\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%C2%BFCuentas_por_cobrar_que_es\"><\/span>\u00bfCuentas por cobrar, que es?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">La Gesti\u00f3n de cuentas por cobrar tiene por objetivo transformar las <strong>Cuentas por Cobrar en activos l\u00edquidos<\/strong> lo m\u00e1s r\u00e1pido posible, revirtiendo el efecto negativo en el flujo de caja o Capital de Trabajo de la empresa. Por lo que, la Gesti\u00f3n de cuentas por cobrar, se basa en realizar un proceso ordenado de pasos que nos permitir\u00e1 organizar el conjunto de acciones, tareas y negociaciones que aplicaremos a los clientes para lograr el recupero de los cr\u00e9ditos vencidos.<\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%C2%BFComo_hacer_una_buena_gestion_de_cuentas_por_cobrar_%E2%80%93_Medir_el_proceso_de_gestion\"><\/span>\u00bfComo hacer una buena gesti\u00f3n de cuentas por cobrar? &#8211; Medir el\u00a0 proceso de gesti\u00f3n.<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">Todo proceso de Gesti\u00f3n de cuentas por cobrar debe ser medido y controlado, por ello es clave utilizar reportes en tiempo real mostrando la evoluci\u00f3n de los principales indicadores de cobranza. Como resultado, en base a estos indicadores o KPI\u00b4s de cobranza, poder ajustar la estrategia de gesti\u00f3n de cobranza, ejecuntando un plan de cobro y haciendo eficiente el trabajo del equipo de gesti\u00f3n de cuentas por cobrar.<\/p>\n<p style=\"text-align: justify;\"><strong>La coordinaci\u00f3n del proceso de la Gesti\u00f3n de cuentas por cobrar se logra utilizando procesos, metodolog\u00eda y buenas pr\u00e1cticas para hacerla en forma eficiente.<\/strong><\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"Definicion_de_la_Gestion_de_cuentas_por_cobrar_%E2%80%93_%C2%BFQue_son_las_cuentas_por_cobrar\"><\/span>Definici\u00f3n de la Gesti\u00f3n de cuentas por cobrar \u2013 \u00bfQue son las cuentas por cobrar?:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">La Gesti\u00f3n de cuentas por cobrar, es el proceso formal mediante el cual se tramita el cobro de una cuenta por concepto de venta de un producto o servicio. El proceso de Gesti\u00f3n de cuentas por cobrar incluye:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Gesti\u00f3n de documentos, facturas, Pagar\u00e9s, Valores<\/li>\n<li>Establecer y utilizar Pol\u00edticas y Procesos de gesti\u00f3n de cuentas por cobrar<\/li>\n<li>Coordinar y utilizar Indicadores de gesti\u00f3n de cuentas por cobrar<\/li>\n<li>Medir la gesti\u00f3n de cobranza con Reportes de Cobranza<\/li>\n<li>Utilizar un Proceso o workflow de Gesti\u00f3n de cobro<\/li>\n<li>Automatizar el proceso con un sistema de Gesti\u00f3n de cuentas por cobrar<\/li>\n<\/ul>\n<figure id=\"attachment_1567\" aria-describedby=\"caption-attachment-1567\" style=\"width: 886px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1567 size-full\" title=\"cuentas por cobrar\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2018\/09\/elementos.png\" alt=\"cuentas por cobrar\" width=\"886\" height=\"488\" srcset=\"https:\/\/debitia.com\/wp-content\/uploads\/2018\/09\/elementos.png 886w, https:\/\/debitia.com\/wp-content\/uploads\/2018\/09\/elementos-300x165.png 300w, https:\/\/debitia.com\/wp-content\/uploads\/2018\/09\/elementos-768x423.png 768w\" sizes=\"auto, (max-width: 886px) 100vw, 886px\" \/><figcaption id=\"caption-attachment-1567\" class=\"wp-caption-text\"><strong>Elementos de la Gesti\u00f3n de Cobranza<\/strong><\/figcaption><\/figure>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"Como_debemos_gestionar_las_cuentas_por_cobrar\"><\/span>Como debemos gestionar las cuentas por cobrar:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul style=\"text-align: justify;\">\n<li>Definir el tipo de deudor<\/li>\n<li>Hacer un seguimiento personalizado<\/li>\n<li>Definir pol\u00edticas, l\u00edmites.<\/li>\n<li>Establecer controles, trazabilidad de las gestiones<\/li>\n<li>Los recursos y equipos<\/li>\n<li>Utilizar los 4 pilares de la gesti\u00f3n de cuentas por cobrar (abajo)<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">El principal objetivo o misi\u00f3n es transformar las <strong>Cuentas por Cobrar en activos l\u00edquidos<\/strong> lo m\u00e1s r\u00e1pido posible, revirtiendo el efecto negativo en el flujo de caja o Capital de Trabajo de la empresa. Por esa raz\u00f3n, la Gesti\u00f3n de cuentas por cobrar, se basa en un proceso ordenado de pasos, que deber\u00e1 ajustarse a cada tipo de empresa, industria o pa\u00eds, ya que no todas las empresas son iguales y los morosos tampoco.<\/p>\n<p style=\"text-align: justify;\">La utilizaci\u00f3n de pol\u00edticas, indicadores y reportes de gesti\u00f3n de cobro, permiten medir el desempe\u00f1o y son el marco a partir del cual podemos planificar la gesti\u00f3n de cuentas por cobrar y ejecutarla mediante una estrategia de cobranza. Eso permitir\u00e1\u00a0 definir y estandarizar procesos, medirlos y controlarlos.<\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%C2%BFQue_hemos_visto_en_distintos_clientes\"><\/span>\u00bfQue hemos visto en distintos clientes?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">En Debitia hemos volcado mas de 10 a\u00f1os de experiencia y el feedback recibido por clientes en la gesti\u00f3n de cuentas por cobrar y en ayudar a cientos de clientes en toda latinoamerica a organizar su proceso de gesti\u00f3n de cobranza, hemos volcado esa experiencia para realizar esta gu\u00eda, que podr\u00e1 utilizar sin importar el tipo de cliente moroso que tenga.<\/p>\n<p style=\"text-align: justify;\">Contamos con clientes en Bancos, telcos, fintechs y Empresas comerciales por supuesto. Esperamos poder ayudarlo a implementar un proceso de cobranza eficiente. Por \u00faltimo,\u00a0 al final del art\u00edculo,le comentamos de que forma estamos ayudando a todo tipo de empresa a gestionar la cobranza.<\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"_%C2%BFComo_hacer_una_buena_gestion_de_cuentas_por_cobrar\"><\/span>\u00a0\u00bfComo hacer una buena gesti\u00f3n de cuentas por cobrar?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">El proceso de cobranza esta basado en la utilizaci\u00f3n de un Pol\u00edtica de cuentas por cobrar. Es usual utilizar\u00a0 distintos canales (llamado telef\u00f3nico, mail, sms, cartas, whatsApp y otros medios) para informarles el estado de sus facturas o cr\u00e9ditos, la obligaci\u00f3n de pago y ofrecerles opciones de normalizaci\u00f3n y pago integradas. Por esta raz\u00f3n, el proceso de cobranza <strong>busca el equilibrio entre cobrar r\u00e1pido y mantener la relaci\u00f3n con el cliente. <\/strong><\/p>\n<figure id=\"attachment_2714\" aria-describedby=\"caption-attachment-2714\" style=\"width: 1920px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2714 size-full\" title=\"cuentas por cobrar\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-home-sistema-de-cobranzas-2020.jpg\" alt=\"cuentas por cobrar\" width=\"1920\" height=\"900\" srcset=\"https:\/\/debitia.com\/wp-content\/uploads\/2020\/04\/debitia-home-sistema-de-cobranzas-2020.jpg 1920w, https:\/\/debitia.com\/wp-content\/uploads\/2020\/04\/debitia-home-sistema-de-cobranzas-2020-300x141.jpg 300w, https:\/\/debitia.com\/wp-content\/uploads\/2020\/04\/debitia-home-sistema-de-cobranzas-2020-1024x480.jpg 1024w, https:\/\/debitia.com\/wp-content\/uploads\/2020\/04\/debitia-home-sistema-de-cobranzas-2020-768x360.jpg 768w, https:\/\/debitia.com\/wp-content\/uploads\/2020\/04\/debitia-home-sistema-de-cobranzas-2020-1536x720.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><figcaption id=\"caption-attachment-2714\" class=\"wp-caption-text\">Sistema de Gesti\u00f3n de Cobranzas<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>En otra publicaci\u00f3n compartimos las<\/strong> <a href=\"https:\/\/debitia.com.ar\/estrategia-de-cobranzas\/\">ESTRATEGIA DE COBRANZAS<\/a><strong>\u00a0 y en otro <\/strong><a href=\"https:\/\/debitia.com.ar\/claves-de-cobranza\/\">CLAVES DE UN PROCESO DE COBRANZA EFECTIVA <\/a><\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"Coordinacion\"><\/span><strong>Coordinaci\u00f3n:<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\"><strong>Es por eso que debemos incluir en el proceso de cobranza la automatizaci\u00f3n del env\u00edo de Mails, SMS, o WhatsApp dentro de una estrategia integrada y coordinada. Que permita la autogesti\u00f3n de los clientes mediante la utilizaci\u00f3n de Landing pages y chatbots de whatsapp.<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"lazy loaded alignnone wp-image-3186\" title=\"cuentas por cobrar\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/06\/Chatbot-de-cobranzas-.png\" sizes=\"auto, (max-width: 553px) 100vw, 553px\" srcset=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/06\/Chatbot-de-cobranzas-.png 486w, https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/06\/Chatbot-de-cobranzas--300x204.png 300w\" alt=\"cuentas por cobrar\" width=\"553\" height=\"377\" data-src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/06\/Chatbot-de-cobranzas-.png\" data-srcset=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/06\/Chatbot-de-cobranzas-.png 486w, https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/06\/Chatbot-de-cobranzas--300x204.png 300w\" data-sizes=\"(max-width: 553px) 100vw, 553px\" data-was-processed=\"true\" \/><img loading=\"lazy\" decoding=\"async\" class=\"lazy loaded alignnone wp-image-3117\" title=\"cuentas por cobrar\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/06\/whats.png\" sizes=\"auto, (max-width: 452px) 100vw, 452px\" srcset=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/06\/whats.png 885w, https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/06\/whats-300x254.png 300w, https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/06\/whats-768x651.png 768w\" alt=\"cuentas por cobrar\" width=\"452\" height=\"383\" data-src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/06\/whats.png\" data-srcset=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/06\/whats.png 885w, https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/06\/whats-300x254.png 300w, https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/06\/whats-768x651.png 768w\" data-sizes=\"(max-width: 452px) 100vw, 452px\" data-was-processed=\"true\" \/><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"lazy loaded alignnone wp-image-3210\" title=\"Gesti\u00f3n de cuentas por cobrar\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2018\/08\/Landing-Debitia.png\" sizes=\"auto, (max-width: 1003px) 100vw, 1003px\" srcset=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2018\/08\/Landing-Debitia.png 885w, https:\/\/debitia.com.ar\/wp-content\/uploads\/2018\/08\/Landing-Debitia-300x106.png 300w, https:\/\/debitia.com.ar\/wp-content\/uploads\/2018\/08\/Landing-Debitia-768x272.png 768w\" alt=\"Gesti\u00f3n de cuentas por cobrar\" width=\"1003\" height=\"355\" data-src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2018\/08\/Landing-Debitia.png\" data-srcset=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2018\/08\/Landing-Debitia.png 885w, https:\/\/debitia.com.ar\/wp-content\/uploads\/2018\/08\/Landing-Debitia-300x106.png 300w, https:\/\/debitia.com.ar\/wp-content\/uploads\/2018\/08\/Landing-Debitia-768x272.png 768w\" data-sizes=\"(max-width: 1003px) 100vw, 1003px\" data-was-processed=\"true\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>La falta coordinaci\u00f3n, de comunicaci\u00f3n e integraci\u00f3n entre los distintos equipos y \u00e1reas de la empresa, sumado al deficiente contacto y uso de los canales digitales con los clientes morosos hace que este proceso sea arduo. Si a esto le sumamos que su equipo puede encuentrarse trabando en forma remota, la coordinaci\u00f3n se vuelve fundamental.<\/strong><\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%C2%BFComo_dar_soporte_a_la_Gestion_de_cuentas_por_cobrar\"><\/span>\u00bfComo dar soporte a la Gesti\u00f3n de cuentas por cobrar?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">Para realizar el proceso de Cobranzas, sugerimos incluir <strong>elementos<\/strong> que deber\u00edan integrar un proceso de Gesti\u00f3n de Cobranzas. Estos elementos ayudan a organizar las definiciones que luego se utilizar\u00e1n al momento de definir un proceso de gesti\u00f3n de cobranzas. Es recomendable analizar si actualmente se los esta considerando en el proceso de cobro de deuda.<\/p>\n<p style=\"text-align: justify;\">1- La utilizaci\u00f3n de pol\u00edticas, t\u00e9cnicas e indicadores de desempe\u00f1o son el marco a partir del cual podemos definir la estrategia de cobranza. Nos permitir\u00e1 definir y estandarizar procesos, medirlos y controlarlos. Establecer cursos de acci\u00f3n que sean : Predecibles, medibles y controlables.<\/p>\n<p style=\"text-align: justify;\">2- Por lo que, definir y establecer etapas o pasos mediante una <strong>Estrategia de Cobranza<\/strong><em><strong>,<\/strong><\/em> permitir\u00e1 organizar el conjunto de acciones, tareas y negociaciones que aplicaremos a los clientes para lograr el recupero de los cr\u00e9ditos vencidos.<\/p>\n<p style=\"text-align: justify;\">3- Establecer y coordinar responsables y recursos que se van a utilizar en la gesti\u00f3n. Establecer los controles, limites y que tendr\u00e1n los analistas en la gesti\u00f3n y negociaci\u00f3n con los clientes.<\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%C2%BFComo_organizar_las_Cuentas_por_Cobrar_%E2%80%93_%C2%BFCuales_son_los_metodos_de_cobranza\"><\/span>\u00bfComo organizar las Cuentas por Cobrar? \u2013 \u00bfCuales son los m\u00e9todos de cobranza?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">Los m\u00e9todos de cobranza o estrategia de cobranza son el conjunto de acciones que permite Organizar, Coordinar y realizar acciones que permitan hacer la cobranza de la cartera en forma sistematizada. Las m\u00e9todos o estrategias de gesti\u00f3n de cobranza, deben ser flexibles y tomar en cuenta los recursos que contamos, la forma y los canales con los que interactuamos con el cliente, su vocaci\u00f3n de pago y la forma que que la empresa quiere trabajar, que no es otra cosa que su p\u00f3litica de cobranzas, la ejecuci\u00f3n del plan de cobranza es la base de un proceso de cobranza organizado.<\/p>\n<p style=\"text-align: justify;\">Debemos definir la forma o <strong>estrategia<\/strong>, en que queremos contactarlos y la coordinaci\u00f3n y seguimiento a las acciones previas. De esta manera, elegir con mayor precisi\u00f3n los canales de comunicaci\u00f3n y las soluciones de pago que m\u00e1s se ajusten a sus necesidades.<\/p>\n<p style=\"text-align: justify;\"><strong>La\u00a0<b>estrategia de cobranza<\/b>\u00a0define las acciones a aplicar y la coordinaci\u00f3n de recursos a utilizar. <\/strong><strong>La utilizaci\u00f3n de pol\u00edticas e indicadores de desempe\u00f1o son el marco a partir del cual podemos definir la\u00a0<b>estrategia de cobranza<\/b>. Nos permitir\u00e1 definir y estandarizar procesos, medirlos y controlarlos. Permitir\u00e1 apalancar la cobranza y hacerla efectiva.<\/strong><\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"Workflow_de_Gestion_de_Cobro_Omnicanal\"><\/span>Workflow de Gesti\u00f3n de Cobro Omnicanal<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">Debe lograr que cada persona de su equipo sepa cual es la pr\u00f3xima\u00a0 gesti\u00f3n a realizar, que el\u00a0 supervisor pueda evaluar el trabajo que cada uno hace desde su casa y los ayude a ser mas eficientes, corrija las estrategias de cobranzas y le de la posibilidad a los clientes que gestionen desde sus casas administrando los reclamos y ofreciendo medios de pago.<\/p>\n<p style=\"text-align: justify;\"><strong>El software de Cobranza Debitia,\u00a0 le permitir\u00e1 definir y establecer etapas o pasos mediante una Estrategia de Cobranza<em>,<\/em>\u00a0le permitir\u00e1 organizar el conjunto de acciones, tareas y negociaciones que aplicaremos a los clientes para lograr el recupero de los cr\u00e9ditos vencidos, ahorrando timpos y costos innecesarios.<br \/>\n<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Sugerimos la lectura de un art\u00edculo dedicado\u00a0a\u00a0 la\u00a0<a href=\"https:\/\/debitia.com.ar\/estrategia-de-cobranzas\/\">ESTRATEGIA DE COBRANZA<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2283 size-full lazy loaded\" title=\"SISTEMA DE GESTI\u00d3N DE COBRANZAS ONLINE\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2019\/01\/gestion-de-cobranzas-marzo.png\" sizes=\"auto, (max-width: 885px) 100vw, 885px\" srcset=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2019\/01\/gestion-de-cobranzas-marzo.png 885w, https:\/\/debitia.com.ar\/wp-content\/uploads\/2019\/01\/gestion-de-cobranzas-marzo-300x100.png 300w, https:\/\/debitia.com.ar\/wp-content\/uploads\/2019\/01\/gestion-de-cobranzas-marzo-768x255.png 768w\" alt=\"Software para Gesti\u00f3n de Cobranzas Debitia\" width=\"885\" height=\"294\" data-src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2019\/01\/gestion-de-cobranzas-marzo.png\" data-srcset=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2019\/01\/gestion-de-cobranzas-marzo.png 885w, https:\/\/debitia.com.ar\/wp-content\/uploads\/2019\/01\/gestion-de-cobranzas-marzo-300x100.png 300w, https:\/\/debitia.com.ar\/wp-content\/uploads\/2019\/01\/gestion-de-cobranzas-marzo-768x255.png 768w\" data-sizes=\"(max-width: 885px) 100vw, 885px\" data-was-processed=\"true\" \/><\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%C2%BFAun_realiza_la_Gestion_de_cuentas_por_cobrar_con_Excel\"><\/span>\u00bfA\u00fan realiza\u00a0 la Gesti\u00f3n de cuentas por cobrar con Excel?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">El Programa de Cobranza Debitia, permite la Gesti\u00f3n de cuentas por cobrar con excel. Esto es organizar el Proceso de Gesti\u00f3n de cuentas por cobrar en un sistema o software de cobranza, pero integrando al excel en la reporteria o en sus macros en forma online.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00bfGestionas cobranzas con Excel? con debitia puedes usar tu informaci\u00f3n en tiempo real y hacer reportes con Excel.<\/strong><\/p>\n<p style=\"text-align: justify;\">El sistema de cuentas por cobrar se encargar\u00e1 de organizar todo el proceso de gesti\u00f3n de cobranza utilizando un conjunto de estrategias, t\u00e9cnicas y metodos eficientes a fin de reducir los plazos de cobro y el costo asociado al proceso de recuperaci\u00f3n de la cartera de Cobranza. En excel expondra en forma online la informaci\u00f3n que le permita tomar decisiones mediante resportes de gesti\u00f3n de cobranza ad hoc.<\/p>\n<p style=\"text-align: justify;\">Por lo que el Programa de Cobranza Debitia, le permitir\u00e1 analizar mediante excel en forma online toda la informaci\u00f3n y le va a permitir definir las acciones, tareas de su equipo de cobranza permitiendo la coordinaci\u00f3n de recursos y programa la gestion de cuentas por cobrar.<\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"Utilice_un_programa_que_permita_la_Gestion_de_cuentas_por_cobrar_con_excel\"><\/span>Utilice un programa que permita la Gesti\u00f3n de cuentas por cobrar con excel:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul style=\"text-align: justify;\">\n<li>Sumar el an\u00e1lisis en excel a la gesti\u00f3n de cuentas por cobrar de Debitia.<\/li>\n<li>Organizar indicadores de Gesti\u00f3n de cuentas por cobrar en excel.<\/li>\n<li>Utilizar el Dashboard de cuentas por cobrar en excel que ya utiliza, integrado a Debitia.<\/li>\n<li>Realizar el control del pago de las cuotas y verlo en excel.<\/li>\n<li>Utilizar reportes standard de Debitia y un dashboard de Gesti\u00f3n de cuentas por cobrar online en excel.<\/li>\n<li>Realizar el control de credito y cartera actualizado en excel con nuestra api de Gesti\u00f3n de cuentas por cobrar.<\/li>\n<li>Disponer de nuestro Chatbot de Gesti\u00f3n de cuentas por cobrar en WhatsApp<\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"NUESTRA_PROPUESTA\"><\/span><strong>NUESTRA PROPUESTA:<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\"><b><strong>Disponibilizar un Software para Cobranza y ayudarlo a utilizar las mejores pr\u00e1cticas y estrategias de Gesti\u00f3n de Cuentas por Cobrar. Recuperar su dinero, coordinar y supervisar su equipo de trabajo, aun gestionando en forma remota. Coordinar una estrategia que incluya canales digitales, ChatBots en WhatsApp, mail, SMS, en forma integrada y efectiva.<\/strong><\/b><\/p>\n<p style=\"text-align: justify;\"><strong>Ya ayudamos a Empresas, Telcos, Bancos, Bancos Digitales y Fintech de Cr\u00e9dito en toda Am\u00e9rica Latina.<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2474 lazy loaded\" title=\"SOFTWARE DE COBRANZA\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-clientes.png\" sizes=\"auto, (max-width: 1074px) 100vw, 1074px\" srcset=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-clientes.png 1200w, https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-clientes-300x35.png 300w, https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-clientes-1024x119.png 1024w, https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-clientes-768x90.png 768w\" alt=\"SOFTWARE DE COBRANZA\" width=\"1074\" height=\"125\" data-src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-clientes.png\" data-srcset=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-clientes.png 1200w, https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-clientes-300x35.png 300w, https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-clientes-1024x119.png 1024w, https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-clientes-768x90.png 768w\" data-sizes=\"(max-width: 1074px) 100vw, 1074px\" data-was-processed=\"true\" \/><\/p>\n<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2572\" title=\"Que es cobranza\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-saber-lo-que-hace-el-equipo.png\" alt=\"\" width=\"23\" height=\"23\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2571\" title=\"cuentas por cobrar\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-reducir-el-plazo-de-cobro.png\" alt=\"cuentas por cobrar\" width=\"23\" height=\"23\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2570\" title=\"Que es cobranza\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-prevenir-la-mora.png\" alt=\"\" width=\"25\" height=\"25\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2568\" title=\"cuentas por cobrar\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-clientes-importantes-primero.png\" alt=\"cuentas por cobrar\" width=\"24\" height=\"24\" \/>\u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2567\" title=\"GESTION DE CUENTAS POR COBRAR EN EXCEL\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-interactuar-con-el-cliente.png\" alt=\"GESTION DE CUENTAS POR COBRAR EN EXCEL\" width=\"25\" height=\"25\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2564\" title=\"como hacer cobranza\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-organiza-clientes.png\" alt=\"\" width=\"24\" height=\"24\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2548\" title=\"cuentas por cobrar\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-empieza-a-gestionar-ya.png\" alt=\"cuentas por cobrar\" width=\"23\" height=\"23\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2572\" title=\"QUE ES LA GESTION DE cuentas por cobrar\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-saber-lo-que-hace-el-equipo.png\" alt=\"QUE ES LA GESTION DE cuentas por cobrar\" width=\"23\" height=\"23\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2571\" title=\"como gestionar cobranza\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-reducir-el-plazo-de-cobro.png\" alt=\"\" width=\"23\" height=\"23\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2570\" title=\"GESTION DE CUENTAS POR COBRAR EN EXCEL\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-prevenir-la-mora.png\" alt=\"GESTION DE CUENTAS POR COBRAR EN EXCEL\" width=\"25\" height=\"25\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2568\" title=\"cobranza efectiva\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-clientes-importantes-primero.png\" alt=\"\" width=\"24\" height=\"24\" \/>\u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2567\" title=\"cuentas por cobrar\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-interactuar-con-el-cliente.png\" alt=\"cuentas por cobrar\" width=\"25\" height=\"25\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2564\" title=\"Que es cobranza\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-organiza-clientes.png\" alt=\"Que es cobranza\" width=\"24\" height=\"24\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2548\" title=\"QUE ES LA GESTION DE COBRANZAS\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-empieza-a-gestionar-ya.png\" alt=\"QUE ES LA GESTION DE COBRANZAS\" width=\"23\" height=\"23\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2568\" title=\"que es cobranza\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-clientes-importantes-primero.png\" alt=\"QUE ES LA COBRANZA\" width=\"24\" height=\"24\" \/>\u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2567\" title=\"cuentas por cobrar\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-interactuar-con-el-cliente.png\" alt=\"cuentas por cobrar\" width=\"25\" height=\"25\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2564\" title=\"Que es cobranza\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-organiza-clientes.png\" alt=\"Que es cobranza\" width=\"24\" height=\"24\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2548\" title=\"QUE ES LA GESTION DE COBRANZAS\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-empieza-a-gestionar-ya.png\" alt=\"QUE ES LA GESTION DE COBRANZAS\" width=\"23\" height=\"23\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2548\" title=\"GESTION DE CUENTAS POR COBRAR EN EXCEL\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-empieza-a-gestionar-ya.png\" alt=\"GESTION DE CUENTAS POR COBRAR EN EXCEL\" width=\"23\" height=\"23\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2568\" title=\"QUE ES LA GESTION DE cuentas por cobrar\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-clientes-importantes-primero.png\" alt=\"QUE ES LA GESTION DE cuentas por cobrar\" width=\"24\" height=\"24\" \/>\u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2567\" title=\"GESTION DE CUENTAS POR COBRAR EN EXCEL\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-interactuar-con-el-cliente.png\" alt=\"GESTION DE CUENTAS POR COBRAR EN EXCEL\" width=\"25\" height=\"25\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2564\" title=\"Que es cobranza\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-organiza-clientes.png\" alt=\"Que es cobranza\" width=\"24\" height=\"24\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2548\" title=\"GESTION DE CUENTAS POR COBRAR EN EXCEL\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-empieza-a-gestionar-ya.png\" alt=\"GESTION DE CUENTAS POR COBRAR EN EXCEL\" width=\"23\" height=\"23\" \/><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>LO ESPERAMOS EN NUESTRA PAGINA (CLICK\u00a0 EN LA FOTO DE ABAJO)<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/debitia.com.ar\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2799 size-full\" title=\"Sistema de Gesti\u00f3n de Cobranzas\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2019\/01\/Pagina-princial.png\" alt=\"Sistema de Gesti\u00f3n de Cobranzas\" width=\"886\" height=\"502\" srcset=\"https:\/\/debitia.com\/wp-content\/uploads\/2019\/01\/Pagina-princial.png 886w, https:\/\/debitia.com\/wp-content\/uploads\/2019\/01\/Pagina-princial-300x170.png 300w, https:\/\/debitia.com\/wp-content\/uploads\/2019\/01\/Pagina-princial-768x435.png 768w\" sizes=\"auto, (max-width: 886px) 100vw, 886px\" \/><\/a><\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"Tiene_consultas_queremos_saber_si_tambien_podemos_ayudarloa_haga_Click_en_la_foto_y_charlamos\"><\/span><span style=\"font-size: 16px;\">Tiene consultas, queremos saber si tambi\u00e9n podemos ayudarlo\/a haga Click en la foto y charlamos !<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<figure id=\"attachment_818\" aria-describedby=\"caption-attachment-818\" style=\"width: 345px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/api.whatsapp.com\/send?phone=5491141891939&amp;text=Quiero%20recibir%20m\u00e1s%20informaci\u00f3n%20sobre%20Debitia%20gracias!%20Mi%20nombre%20es\u2026%20\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-818\" title=\"Gesti\u00f3n de Cobranzas\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2018\/09\/Pongase-en-contacto-con-German-Morilla.png\" alt=\"Qu\u00e9 es la Gesti\u00f3n de Cobranzas\" width=\"345\" height=\"155\" srcset=\"https:\/\/debitia.com\/wp-content\/uploads\/2018\/09\/Pongase-en-contacto-con-German-Morilla.png 885w, https:\/\/debitia.com\/wp-content\/uploads\/2018\/09\/Pongase-en-contacto-con-German-Morilla-300x135.png 300w, https:\/\/debitia.com\/wp-content\/uploads\/2018\/09\/Pongase-en-contacto-con-German-Morilla-768x345.png 768w\" sizes=\"auto, (max-width: 345px) 100vw, 345px\" \/><\/a><figcaption id=\"caption-attachment-818\" class=\"wp-caption-text\"><strong>Lo ayudamos en la Gesti\u00f3n de Cobranzas<\/strong><\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><strong>Que es la gesti\u00f3n de cuentas por cobrar. Sabe que es la gesti\u00f3n de cuentas por cobrar<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">","protected":false},"excerpt":{"rendered":"<p>Cuentas por Cobrar \u00bfCuentas por cobrar, que es? La Gesti\u00f3n de cuentas por cobrar tiene por objetivo transformar las Cuentas por Cobrar en activos l\u00edquidos lo m\u00e1s r\u00e1pido posible, revirtiendo el efecto negativo en el flujo de caja o Capital de Trabajo de la empresa. Por lo que, la Gesti\u00f3n de cuentas por cobrar, se&hellip;<\/p>","protected":false},"author":5,"featured_media":3186,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_series":[],"class_list":["post-5856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","entry","has-media"],"_links":{"self":[{"href":"https:\/\/debitia.com\/es_us\/wp-json\/wp\/v2\/posts\/5856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/debitia.com\/es_us\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/debitia.com\/es_us\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/debitia.com\/es_us\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/debitia.com\/es_us\/wp-json\/wp\/v2\/comments?post=5856"}],"version-history":[{"count":0,"href":"https:\/\/debitia.com\/es_us\/wp-json\/wp\/v2\/posts\/5856\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/debitia.com\/es_us\/wp-json\/wp\/v2\/media\/3186"}],"wp:attachment":[{"href":"https:\/\/debitia.com\/es_us\/wp-json\/wp\/v2\/media?parent=5856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/debitia.com\/es_us\/wp-json\/wp\/v2\/categories?post=5856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/debitia.com\/es_us\/wp-json\/wp\/v2\/tags?post=5856"},{"taxonomy":"post_series","embeddable":true,"href":"https:\/\/debitia.com\/es_us\/wp-json\/wp\/v2\/post_series?post=5856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}