{"id":6134,"date":"2020-01-17T11:59:51","date_gmt":"2020-01-17T14:59:51","guid":{"rendered":"https:\/\/debitia.com\/?p=6134"},"modified":"2024-04-17T13:07:40","modified_gmt":"2024-04-17T16:07:40","slug":"definicion-de-gestion-de-cobranza","status":"publish","type":"post","link":"https:\/\/debitia.com\/es_do\/definicion-de-gestion-de-cobranza\/","title":{"rendered":"Definici\u00f3n de Gesti\u00f3n de Cobranza \u00bfComo realizarla?"},"content":{"rendered":"<div class=\"entry-content\" style=\"text-align: justify;\">\n<figure id=\"attachment_6774\" aria-describedby=\"caption-attachment-6774\" style=\"width: 1999px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6774 size-full\" title=\"Gesti\u00f3n de cuentas por cobrar\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2023\/11\/listado-de-cuentas-por-cobtrar.png\" alt=\"Gesti\u00f3n de cuentas por cobrar\" width=\"1999\" height=\"743\" \/><figcaption id=\"caption-attachment-6774\" class=\"wp-caption-text\">Listado de cuentas por cobrar<\/figcaption><\/figure>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/debitia.com\/es_do\/definicion-de-gestion-de-cobranza\/#%C2%BFComo_realizar_la_Gestion_de_Cobranza_por_WhatsApp\" >\u00bfComo realizar la Gesti\u00f3n de Cobranza por WhatsApp?<\/a><ul class='ez-toc-list-level-2' ><li class='ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/debitia.com\/es_do\/definicion-de-gestion-de-cobranza\/#%C2%BFQue_es_la_cobranza_por_WhatsApp_%C2%BFcomo_puede_impactar_la_gestion_de_cobranza\" >\u00bfQue es la cobranza por WhatsApp? \u00bfcomo puede impactar la gesti\u00f3n de cobranza?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/debitia.com\/es_do\/definicion-de-gestion-de-cobranza\/#%C2%BFQue_es_la_gestion_de_cobranza_y_cual_es_su_importancia\" >\u00bfQu\u00e9 es la gesti\u00f3n de cobranza y cual es su importancia?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/debitia.com\/es_do\/definicion-de-gestion-de-cobranza\/#%C2%BFQue_es_la_gestion_de_cobranza_%E2%80%93_Objetivos\" >\u00bfQue es la gesti\u00f3n de cobranza? &#8211; Objetivos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/debitia.com\/es_do\/definicion-de-gestion-de-cobranza\/#Definicion_de_la_Gestion_de_cobranzas_%E2%80%93_%C2%BFQue_son_las_cuentas_por_cobrar\" >Definici\u00f3n de la Gesti\u00f3n de cobranzas \u2013 \u00bfQue son las cuentas por cobrar?:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/debitia.com\/es_do\/definicion-de-gestion-de-cobranza\/#Importancia_de_la_gestion_de_cuentas_por_cobrar\" >Importancia de la gesti\u00f3n de cuentas por cobrar<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/debitia.com\/es_do\/definicion-de-gestion-de-cobranza\/#Consecuencias_de_definir_mal_la_gestion_de_cobranzas\" >Consecuencias de definir mal la gesti\u00f3n de cobranzas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/debitia.com\/es_do\/definicion-de-gestion-de-cobranza\/#Optimiza_tu_gestion_de_cobranza_con_estas_practicas_efectivas\" >Optimiza tu gesti\u00f3n de cobranza con estas pr\u00e1cticas efectivas<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/debitia.com\/es_do\/definicion-de-gestion-de-cobranza\/#1_Toma_medidas_preventivas\" >1. Toma medidas preventivas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/debitia.com\/es_do\/definicion-de-gestion-de-cobranza\/#2_Disena_y_ejecuta_tu_estrategia_de_cobranzas_en_forma_automatica\" >2. Dise\u00f1a y ejecuta tu estrategia de cobranzas en forma autom\u00e1tica<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/debitia.com\/es_do\/definicion-de-gestion-de-cobranza\/#3_Arma_una_base_de_datos_de_tus_clientes\" >3. Arma una base de datos de tus clientes<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/debitia.com\/es_do\/definicion-de-gestion-de-cobranza\/#4_Elabora_y_define_bien_tus_politicas_y_procesos_de_gestion_de_cobranza_para_recuperar_la_cartera_vencida\" >4. Elabora y define bien tus pol\u00edticas y procesos de gesti\u00f3n de cobranza para recuperar la cartera vencida<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/debitia.com\/es_do\/definicion-de-gestion-de-cobranza\/#%C2%BFQue_son_los_mensajes_de_cobranza_por_whatsapp\" >\u00bfQue son los mensajes de cobranza por whatsapp?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/debitia.com\/es_do\/definicion-de-gestion-de-cobranza\/#Ejemplo_de_mensaje_de_cobranza_por_WhatsApp\" >Ejemplo de mensaje de cobranza por WhatsApp<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/debitia.com\/es_do\/definicion-de-gestion-de-cobranza\/#Automatice_el_proceso_de_Gestion_de_Cobranza_con_Debitia\" >Automatice el proceso de Gesti\u00f3n de Cobranza con Debitia:<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h1 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%C2%BFComo_realizar_la_Gestion_de_Cobranza_por_WhatsApp\"><\/span><strong><span style=\"font-size: 21px;\">\u00bfComo realizar la <span style=\"color: #ff6600;\">Gesti\u00f3n de Cobranza por WhatsApp<\/span>?<\/span><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h1>\n<p><strong>Todo el proceso de gesti\u00f3n de <a href=\"https:\/\/debitia.com.ar\/cuentas-por-cobrar\/\">cobranza por whatsapp<\/a> explicado en este art\u00edculo forma parte de la experiencia que hemos volcado en el <a href=\"https:\/\/debitia.com.ar\/sistema-de-cobranzas\/\">sistema de cobranzas<\/a><\/strong> <strong>Debitia.<\/strong> Debitia administra <a href=\"https:\/\/debitia.com.ar\/que-es-la-cartera-de-cobranzas\/\"><strong>carteras de cobranza<\/strong><\/a> de diversos tama\u00f1os\u00a0 e industrias y permite el uso de <a href=\"https:\/\/debitia.com.ar\/estrategias-de-cobranza\/\"><strong>estrategias de cobranzas<\/strong><\/a> que van a coordinar todo el proceso de cobranza que aqu\u00ed explicaremos. La utilizaci\u00f3n y coordinaci\u00f3n de los canales de contacto como SMS, mail, WhatsApp esta coordinada en Debitia. <strong>La elaboraci\u00f3n y envi\u00f3 de mensajes de cobranza por whatsapp tambi\u00e9n es administrado en Debitia.<\/strong><\/p>\n<p><span style=\"font-size: 18px;\"><strong>Haremos un introducci\u00f3n y definici\u00f3n del la gesti\u00f3n de cuentas por cobrar y luego si, explicaremos como realizar la gesti\u00f3n de cuentas por cobrar con WhatsApp en un software de cobranzas.<\/strong><\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFQue_es_la_cobranza_por_WhatsApp_%C2%BFcomo_puede_impactar_la_gestion_de_cobranza\"><\/span><span style=\"font-size: 21px;\">\u00bfQue es la <span style=\"color: #ff6600;\">cobranza por WhatsApp<\/span>? \u00bfcomo puede impactar la gesti\u00f3n de cobranza?<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">La automatizaci\u00f3n de las comunicaciones con el cliente se ha convertido en una de las principales estrategias que las instituciones l\u00edderes est\u00e1n empleando en cobranzas. En este contexto, una software de cobranzas integrado a WhatsApp, ofrece oportunidades innovadoras para las estrategias de cobranzas ya que ademas de automatizar el envi\u00f3 registra en la bit\u00e1cora o ficha del cliente todas las gestiones. El Proceso de env\u00edo de mensajes de cobranza por WhatsApp se puede realizar desde\u00a0 su cuenta personal o la corporativa.<\/p>\n<h2><span style=\"font-size: 21px; color: #000000;\">\u00bfQu\u00e9 es la gesti\u00f3n de cobranza y cual es su importancia?<\/span><strong><br \/>\n<\/strong><\/h2>\n<div class=\"blog-post__body clear\">\n<p style=\"text-align: justify;\">La definici\u00f3n de la gesti\u00f3n de cobranza es el <b>conjunto de estrategias y acciones dise\u00f1adas para asegurar que los clientes paguen sus deudas en tiempo<\/b>, lo que garantiza la liquidez de la empresa y su capacidad para financiar sus operaciones. En otras palabras, surgen cuando se entrega un producto o servicio y se permite al cliente pagar en un per\u00edodo posterior. Cobro oportuno de pagos: una de las razones principales para administrar las cuentas por cobrar es <b>garantizar el cobro oportuno de los pagos de los clientes<\/b>. Los pagos retrasados \u200b\u200bpueden crear problemas de flujo de caja, obstaculizar las operaciones comerciales e incluso provocar dificultades financieras.<\/p>\n<\/div>\n<h2 style=\"text-align: justify;\"><span style=\"font-size: 21px;\">\u00bfQue es la gesti\u00f3n de cobranza? &#8211; Objetivos<br \/>\n<\/span><\/h2>\n<p style=\"text-align: justify;\">La Gesti\u00f3n de Cuentas por Cobrar tiene por objetivo transformar las <strong>Cuentas por Cobrar en activos l\u00edquidos<\/strong> lo m\u00e1s r\u00e1pido posible, revirtiendo el efecto negativo en el flujo de caja o Capital de Trabajo de la empresa. Por lo que, la Gesti\u00f3n de cobranza, se basa en realizar un proceso ordenado de pasos que nos permitir\u00e1 organizar el conjunto de acciones, tareas y negociaciones que aplicaremos a los clientes para lograr el recupero de los cr\u00e9ditos vencidos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1561\" title=\"Gesti\u00f3n de Cobranza\" src=\"https:\/\/debitia.com\/wp-content\/uploads\/2018\/09\/elemento-basicos-GC-2.png\" alt=\"Gesti\u00f3n de Cobranza\" width=\"338\" height=\"190\" srcset=\"https:\/\/debitia.com\/wp-content\/uploads\/2018\/09\/elemento-basicos-GC-2.png 886w, https:\/\/debitia.com\/wp-content\/uploads\/2018\/09\/elemento-basicos-GC-2-300x169.png 300w, https:\/\/debitia.com\/wp-content\/uploads\/2018\/09\/elemento-basicos-GC-2-768x432.png 768w\" sizes=\"auto, (max-width: 338px) 100vw, 338px\" \/> \u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1825\" title=\"Gesti\u00f3n de Cobranza\" src=\"https:\/\/debitia.com\/wp-content\/uploads\/2018\/10\/Gestion-de-cobranzas.png\" alt=\"Gesti\u00f3n de Cobranza\" width=\"370\" height=\"192\" srcset=\"https:\/\/debitia.com\/wp-content\/uploads\/2018\/10\/Gestion-de-cobranzas.png 886w, https:\/\/debitia.com\/wp-content\/uploads\/2018\/10\/Gestion-de-cobranzas-300x156.png 300w, https:\/\/debitia.com\/wp-content\/uploads\/2018\/10\/Gestion-de-cobranzas-768x399.png 768w\" sizes=\"auto, (max-width: 370px) 100vw, 370px\" \/><\/p>\n<\/div>\n<h2><span class=\"ez-toc-section\" id=\"Definicion_de_la_Gestion_de_cobranzas_%E2%80%93_%C2%BFQue_son_las_cuentas_por_cobrar\"><\/span><span style=\"font-size: 21px;\">Definici\u00f3n de la Gesti\u00f3n de cobranzas \u2013 \u00bfQue son las cuentas por cobrar?:<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">La Gesti\u00f3n de cobranzas es el proceso formal mediante el cual se tramita el cobro de una cuenta por concepto de venta de un producto o servicio. En otras palabras, se trata del conjunto de estrategias y acciones dise\u00f1adas para asegurar que los clientes paguen sus deudas en tiempo, lo que garantiza la liquidez de la empresa y su capacidad para financiar sus operaciones. El proceso de Gesti\u00f3n de cobranzas incluye:<\/p>\n<ul>\n<li>Gesti\u00f3n de documentos, facturas, Pagar\u00e9s, Valores, cuentas por cobrar<\/li>\n<li>Establecer y utilizar Pol\u00edticas y Procesos de gesti\u00f3n de cobranza<\/li>\n<li>Coordinar y utilizar Indicadores de gesti\u00f3n de cuentas por cobrar<\/li>\n<li>Medir la gesti\u00f3n de cobranza con Reportes de gesti\u00f3n de cobranza<\/li>\n<li>Utilizar un Proceso o workflow de Gesti\u00f3n de cobro<\/li>\n<li>Gesti\u00f3n de campa\u00f1as de envio de mails, SMS, WhatsApp<\/li>\n<li>Gesti\u00f3n de pagos digitales integrados<\/li>\n<li>Automatizar el proceso con un sistema de Gesti\u00f3n de Cobranzas<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Importancia_de_la_gestion_de_cuentas_por_cobrar\"><\/span><span style=\"font-size: 21px;\">Importancia de la gesti\u00f3n de cuentas por cobrar<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"entry-content\" style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Podemos decir que la <strong>importancia de\u00a0 la gesti\u00f3n de cuentas por cobrar <\/strong>recae en que es una actividad que permite el mantenimiento de clientes y el crecimiento de cualquier empresa. Asimismo, esta no solo permite recuperar el dinero adeudado por los clientes, sino que tambi\u00e9n es una oportunidad para generar una cultura de pago responsable y rentabilidad para el negocio.<\/p>\n<p style=\"text-align: justify;\">Aunque muchas veces la cobranza es vista como el paso final en el ciclo de cr\u00e9ditos, no debe ser as\u00ed; puesto que se trata de una parte integral del mismo; del mismo modo, hay que tener presente que durante la <strong>gesti\u00f3n de cuentas por cobrar<\/strong>, las organizaciones obtienen retroalimentaci\u00f3n acerca de sus pol\u00edticas y actividades espec\u00edficas, lo que permite que puedan realizar mejoras y ajuste en cada subproceso.<\/p>\n<p style=\"text-align: justify;\">Por otro lado, la<strong> gesti\u00f3n de cuentas por cobrar <\/strong>tambi\u00e9n es importante porque puede ser vista como un \u00e1rea de negocio en s\u00ed misma; ya que busca generar rentabilidad convirtiendo las p\u00e9rdidas en ingresos. Esto \u00faltimo se consigue mediante la recuperaci\u00f3n de los montos adeudados, as\u00ed como a trav\u00e9s de la fidelizaci\u00f3n de los clientes, puesto que los clientes satisfechos tender\u00e1n a volver a solicitar servicios o productos a la compa\u00f1\u00eda.<\/p>\n<p>Para garantizar la liquidez de la empresa, es necesario tener un control eficiente de estas cuentas y aplicar estrategias adecuadas para minimizar los riesgos de impago o retrasos en el pago de obligaciones.<\/p>\n<p>El manejo eficiente de las cuentas por cobrar se revela como un componente crucial para asegurar la solidez financiera de cualquier empresa. En este contexto, es esencial comprender qu\u00e9 son las cuentas por cobrar y por qu\u00e9 su adecuada gesti\u00f3n es tan fundamental.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Consecuencias_de_definir_mal_la_gestion_de_cobranzas\"><\/span><span style=\"font-size: 21px;\">Consecuencias de definir mal la gesti\u00f3n de cobranzas<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Una\u00a0<strong>mala gesti\u00f3n de cobranza\u00a0<\/strong>puede llevar a estrategias equivocadas y costosas para tu organizaci\u00f3n; estos son algunos ejemplos de malas pr\u00e1cticas y sus consecuencias:<\/p>\n<ul>\n<li aria-level=\"1\">La refinanciaci\u00f3n, renovaci\u00f3n u otorgar nuevos cr\u00e9ditos sin que el cliente haya cancelado el anterior; puesto que podr\u00eda empeorar la situaci\u00f3n de la cartera en el corto plazo, en especial si no se parte de un an\u00e1lisis detallado.<\/li>\n<li aria-level=\"1\">Cobrar bienes o artefactos como forma de pago; ya que ocasiona la desorientaci\u00f3n del gestor e implica altos costos de almacenaje y administraci\u00f3n de los bienes; asimismo, ocasiona que el cliente tenga una percepci\u00f3n err\u00f3nea del pago de sus obligaciones.<\/li>\n<li aria-level=\"1\">Orientar la cobranza de forma subjetiva; al considerar, por ejemplo, a algunos clientes como p\u00e9rdida total o apelar a la buena voluntad para que estos paguen.<\/li>\n<\/ul>\n<h2><a href=\"https:\/\/debitia.com\/es_do\/sd\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-6781 size-full\" title=\"Gesti\u00f3n de Cobranza\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2021\/11\/Agenda-una-demo.png\" alt=\"Gesti\u00f3n de Cobranza\" width=\"1472\" height=\"150\" \/><\/a><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1222 aligncenter\" src=\"https:\/\/debitia.com\/wp-content\/uploads\/2018\/08\/B2B-DEBITIA.png\" alt=\"\" width=\"738\" height=\"507\" srcset=\"https:\/\/debitia.com\/wp-content\/uploads\/2018\/08\/B2B-DEBITIA.png 886w, https:\/\/debitia.com\/wp-content\/uploads\/2018\/08\/B2B-DEBITIA-300x206.png 300w, https:\/\/debitia.com\/wp-content\/uploads\/2018\/08\/B2B-DEBITIA-768x528.png 768w\" sizes=\"auto, (max-width: 738px) 100vw, 738px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Optimiza_tu_gestion_de_cobranza_con_estas_practicas_efectivas\"><\/span>Optimiza tu gesti\u00f3n de cobranza con estas pr\u00e1cticas efectivas<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>A continuaci\u00f3n, compartimos algunas buenas pr\u00e1cticas que te ayudar\u00e1n a mejorar la gesti\u00f3n de cobranza:<\/p>\n<h3 style=\"padding-left: 40px;\"><span class=\"ez-toc-section\" id=\"1_Toma_medidas_preventivas\"><\/span><span style=\"font-size: 18px;\">1. Toma medidas preventivas<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"padding-left: 40px;\">Es mejor tomar medidas que eviten la morosidad a cobrar cuentas atrasadas. Entre estas medidas, puedes considerar las siguientes:<\/p>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li aria-level=\"1\">Educa al cliente, previo al desembolso, acerca de todo lo que implica adquirir acceder al cr\u00e9dito que le ofreces.<\/li>\n<li aria-level=\"1\">Establece fechas de pago que sean mutuamente beneficiosas.<\/li>\n<li aria-level=\"1\">Atiende a tiempo las quejas y reclamos; algunos clientes insatisfechos tienden a caer en la morosidad a modo de represalia por alg\u00fan producto o servicio con el que est\u00e1n inconformes.<\/li>\n<li aria-level=\"1\">Reconoce y premia a los clientes que cumplen puntualmente con sus pagos.<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<h3 style=\"padding-left: 40px;\"><span class=\"ez-toc-section\" id=\"2_Disena_y_ejecuta_tu_estrategia_de_cobranzas_en_forma_automatica\"><\/span><span style=\"font-size: 18px;\">2. Dise\u00f1a y ejecuta tu <a href=\"https:\/\/debitia.com.ar\/estrategias-de-cobranza\/\">estrategia de cobranzas en forma autom\u00e1tica<\/a><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"padding-left: 40px;\">Define si la cobranza se realizar\u00e1 de forma interna o externa; as\u00ed como las medidas que se tomar\u00e1n para contar con personal capacitado. Por ejemplo:<\/p>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li aria-level=\"1\">Analiza y define el procedimiento de cobranza que realizar\u00e1s.<\/li>\n<li aria-level=\"1\">Si decides crear una unidad interna de cobranza selecciona y capacita a tu personal.<\/li>\n<li aria-level=\"1\">Eval\u00faa la posibilidad de integrar un software de gesti\u00f3n de cobranza que te permita automatizar procesos y reducir errores. \u00a1<a href=\"https:\/\/debitia.com\/es_do\/\">Debitia es una excelente alternativa<\/a>!<\/li>\n<li aria-level=\"1\">Eval\u00faa integrar un sistema de incentivos para los gestores de cobranza.\u00a0 Podr\u00edas brindarles recompensas en base al flujo de recuperaci\u00f3n efectiva.<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<h3 style=\"padding-left: 40px;\"><span class=\"ez-toc-section\" id=\"3_Arma_una_base_de_datos_de_tus_clientes\"><\/span><span style=\"font-size: 18px;\">3. Arma una base de datos de tus clientes<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"padding-left: 40px;\">El \u00e9xito de la gesti\u00f3n de cobranza depende de contar con una base de datos actualizada y ordenada; los sistemas de gesti\u00f3n de cobranza online lo tienen; por lo que, si los implementas, te ayudar\u00e1n a agilizar y optimizar tus procesos de cobros. Las caracter\u00edsticas del soporte inform\u00e1tico de cobranza ideal son:<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li aria-level=\"1\">Que te facilite el monitoreo de clientes y clientes morosos.<\/li>\n<li aria-level=\"1\">Que genere reportes claros y precisos.<\/li>\n<li aria-level=\"1\">Que te brinde un historial de las medidas tomadas.<\/li>\n<li aria-level=\"1\">Que te proporcione diferentes canales de cobranza.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h3 style=\"padding-left: 40px;\"><span style=\"font-size: 18px;\">4. Elabora y define bien tus pol\u00edticas y procesos de gesti\u00f3n de cobranza para recuperar la cartera vencida<br \/>\n<\/span><\/h3>\n<p style=\"padding-left: 40px;\">Establece pol\u00edticas para el contacto con el cliente; implementa una estrategia de cobranza segmentada por niveles de riesgos (\u00a1aqu\u00ed tambi\u00e9n te puede ser de mucha ayuda un <strong>software de cobranza automatizado<\/strong>!). Asimismo, te puede ser \u00fatil ofrecer una variedad de opciones de pago.<\/p>\n<p style=\"padding-left: 40px;\">En resumen, la gesti\u00f3n de cobranza es una actividad esencial para cualquier organizaci\u00f3n, ya que permite el mantenimiento de clientes y el crecimiento del negocio. Adem\u00e1s, una adecuada\u00a0<strong>gesti\u00f3n de las cuentas por cobrar<\/strong>\u00a0puede ayudar a que la organizaci\u00f3n tenga un\u00a0<strong>flujo de caja<\/strong>\u00a0saludable que reduzca sus riesgos financieros. Por otro lado, una\u00a0<strong>mala gesti\u00f3n de cobranza<\/strong> puede llevar a estrategias equivocadas y costosas para la organizaci\u00f3n. Es importante implementar buenas pr\u00e1cticas como acciones preventivas, una buena estrategia de cobranza y una base de datos actualizada y ordenada para mejorar la gesti\u00f3n de cobranza y garantizar el \u00e9xito en la recuperaci\u00f3n de las cuentas por cobrar.<\/p>\n<h2 style=\"text-align: justify;\"><span style=\"font-size: 21px;\"><a href=\"https:\/\/debitia.com\/es_do\/sd\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-6781 size-full\" title=\"Gesti\u00f3n de Cobranza\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2021\/11\/Agenda-una-demo.png\" alt=\"Gesti\u00f3n de Cobranza\" width=\"1472\" height=\"150\" \/><\/a><\/span><\/h2>\n<\/div>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%C2%BFQue_son_los_mensajes_de_cobranza_por_whatsapp\"><\/span><span style=\"font-size: 21px;\">\u00bfQue son los <span style=\"color: #ff6600;\">mensajes de cobranza por whatsapp<\/span>?<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\"><span class=\"BxUVEf ILfuVd\" lang=\"es\"><span class=\"hgKElc\">Los mensajes de cobranza por WhatsApp son una <b>forma de comunicaci\u00f3n utilizada por las empresas para recordar a sus clientes sobre el vencimiento de una factura o el pago de una deuda<\/b>. Los mensajes de cobranza por whatsapp son un nuevo canal para gestionar la cobranza.\u00a0<\/span><\/span><\/p>\n<p style=\"text-align: justify;\">La efectividad de un mensaje de cobranza por WhatsApp dirigido a la recuperaci\u00f3n cuentas por cobrar, radica en su capacidad para captar la atenci\u00f3n del deudor y motivarlo a tomar acci\u00f3n de manera inmediata. Es esencial que el mensaje sea conciso y directo, evitando abrumar al destinatario con informaci\u00f3n superflua. Debitia permite elegir las variables del cliente, de deuda, vencimientos y medios de pago,\u00a0 incluso incluir link a portal de clientes con todos los medios de pago disponibles, para que el cliente abone en forma online su deuda.<\/p>\n<p style=\"text-align: justify;\">Al elaborar el mensaje de cobranza por whatsapp, es importante incluir los siguientes elementos:<\/p>\n<ol>\n<li>Identificaci\u00f3n clara de la empresa o persona responsable de la cobranza.<\/li>\n<li>Menci\u00f3n del importe adeudado seg\u00fan la factura correspondiente.<\/li>\n<li>Establecimiento de la fecha l\u00edmite para el pago.<\/li>\n<li>Recomendaci\u00f3n de los m\u00e9todos de pago disponibles, con \u00e9nfasis en la opci\u00f3n de cobranza por WhatsApp.<\/li>\n<li>Advertencia sobre las posibles repercusiones de no cumplir con el pago dentro del plazo estipulado.<\/li>\n<li>Inclusi\u00f3n de cualquier detalle adicional que pueda persuadir al deudor para que proceda con el pago de manera inmediata.<\/li>\n<\/ol>\n<div class=\"RqBzHd\" style=\"text-align: justify;\">\n<h2><span class=\"ez-toc-section\" id=\"Ejemplo_de_mensaje_de_cobranza_por_WhatsApp\"><\/span><span style=\"font-size: 21px;\">Ejemplo de <span style=\"color: #ff6600;\">mensaje de cobranza por WhatsApp<\/span><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Estimado {{Name}}, este mensaje es un recordatorio de pago, ya que al dia de hoy se encuentra con una deuda de $ {{ActualDebit}} pendiente de pago Agradecemos pueda ponerse en contacto con nosotros y coordinar el pago correspondiente. Saludo<\/p>\n<p>Ejecutado autom\u00e1ticamente por Debitia y registrado en la bit\u00e1cora del cliente, generando historia de sus gestiones autom\u00e1ticas. Pudiendo tomarse m\u00e1s variables, como <b>{DueDays}}<\/b> &#8211; Dias en Mora, <b>{{DueDate}}<\/b> &#8211; Fecha de Mora, por ejemplo.<\/p>\n<\/div>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-6880 size-full\" title=\"Sistema de Cobranzas por WhatsApp\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2023\/01\/Template-WA-con-campos-1.png\" alt=\"Sistema de Cobranzas por WhatsApp\" width=\"1999\" height=\"756\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff6600;\"><strong>Como vemos, la coordinaci\u00f3n entre el armado de los templetes de los mensajes de cobranza, la automatizaci\u00f3n en el env\u00edo y la registraci\u00f3n son las tres piezas fundamentales que hacen que esta herramienta se pueda aprovechar correctamente.<\/strong><\/span><\/p>\n<h2><a href=\"https:\/\/debitia.com\/es_do\/sd\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-6781 size-full\" title=\"Gesti\u00f3n de Cobranza\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2021\/11\/Agenda-una-demo.png\" alt=\"Gesti\u00f3n de Cobranza\" width=\"1472\" height=\"150\" \/><\/a><\/h2>\n<h2><span class=\"ez-toc-section\" id=\"Automatice_el_proceso_de_Gestion_de_Cobranza_con_Debitia\"><\/span><span style=\"font-size: 21px;\"><strong>Automatice el proceso de Gesti\u00f3n de Cobranza con Debitia:<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\"><span data-hs-cos-general-type=\"meta_field\" data-hs-cos-type=\"rich_text\">Con Debitia podr\u00e1s crear estrategias y campa\u00f1as de cobro de acuerdo a la segmentaci\u00f3n de tus clientes por su tipo de riesgo, etapa o el criterio personal que elijas, permiti\u00e9ndote cobrar mejor y de manera autom\u00e1tica. Dispondr\u00e1s de los indicadores de gesti\u00f3n de empresa en todo momento. Tomar decisiones basadas en datos que permitan hacer crecer tu negocio. Enviar recordatorios de pago a trav\u00e9s de email, SMS y mensajes de cobranza por whatsapp y utilizar tu propia web de cobros (portal de clientes) para recaudar los pagos de manera sencilla.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>Estamos presentes en M\u00e9xico y toda Latinoam\u00e9rica.\u00a0 Contamos con la experiencia de haber implementado Debitia en Empresas, Telcos, Bancos, Bancos Digitales y Fintech de Cr\u00e9dito en toda Am\u00e9rica Latina, cumplido con los est\u00e1ndares m\u00e1s altos de seguridad e integridad de la informaci\u00f3n. No deje los datos sensibles de su empresa en manos de software que no tienen probada experiencia en el mercado.<\/strong><\/p>\n<p data-wow-delay=\"0.5s\"><a href=\"https:\/\/debitia.com\/es_do\/sd\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-6724 size-full\" title=\"Gesti\u00f3n de cuentas por cobrar\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2024\/04\/debitia-recortado.png\" alt=\"Gesti\u00f3n de cuentas por cobrar\" width=\"1999\" height=\"822\" \/><\/a><\/p>\n<p data-wow-delay=\"0.5s\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2572 size-full\" title=\"Gesti\u00f3n de cuentas por cobrar\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-saber-lo-que-hace-el-equipo.png\" alt=\"Etapas de la cobranza\" width=\"100\" height=\"100\" \/>\u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2571 size-full\" title=\"Gesti\u00f3n de Cobranza\" src=\"https:\/\/debitia.com\/wp-content\/uploads\/2020\/04\/debitia-beneficios-reducir-el-plazo-de-cobro.png\" alt=\"Gesti\u00f3n de Cobranza\" width=\"100\" height=\"100\" \/>\u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2570 size-full\" title=\"Definici\u00f3n de gesti\u00f3n de cobranza\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-prevenir-la-mora.png\" alt=\"Definici\u00f3n de gesti\u00f3n de cobranza\" width=\"100\" height=\"100\" \/>\u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2568 size-full\" title=\"Gesti\u00f3n de cuentas por cobrar\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-clientes-importantes-primero.png\" alt=\"Gesti\u00f3n de cuentas por cobrar\" width=\"100\" height=\"100\" \/>\u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2567 size-full\" title=\"Definici\u00f3n de gesti\u00f3n de cobranza\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-interactuar-con-el-cliente.png\" alt=\"Definici\u00f3n de gesti\u00f3n de cobranza\" width=\"100\" height=\"100\" \/>\u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2564 size-full\" title=\"Gesti\u00f3n de Cobranza\" src=\"https:\/\/debitia.com\/wp-content\/uploads\/2020\/04\/debitia-beneficios-organiza-clientes.png\" alt=\"Gesti\u00f3n de Cobranza\" width=\"100\" height=\"100\" \/><\/p>\n<p class=\"title wow slideInLeft\" style=\"text-align: justify;\" data-wow-delay=\"0.5s\"><span style=\"font-size: 9px; color: #ffffff;\">Ejecutar un Proceso de Cobranza Eficiente en 7 pasos. Claves para un Proceso de Cobranza Eficiente en 10 Pasos. software de cobranzas. <\/span><span class=\"white-text\" style=\"font-size: 21px;\"><span style=\"font-size: 9px; color: #ffffff;\">Seguir un Proceso de Cobranza EFICIENTE. sistema de cobranzas y software de Cobranza efectiva. Coordinar el proceso de cobro o gesti\u00f3n de cobro con estrategias de cobranzas. Sistema de Cobranzas y software de cobranzas efectivo o cobranza eficiente<\/span><br \/>\n<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>\u00bfComo realizar la Gesti\u00f3n de Cobranza por WhatsApp? Todo el proceso de gesti\u00f3n de cobranza por whatsapp explicado en este art\u00edculo forma parte de la experiencia que hemos volcado en el sistema de cobranzas Debitia. Debitia administra carteras de cobranza de diversos tama\u00f1os\u00a0 e industrias y permite el uso de estrategias de cobranzas que van&hellip;<\/p>","protected":false},"author":5,"featured_media":6137,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_series":[],"class_list":["post-6134","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","entry","has-media"],"_links":{"self":[{"href":"https:\/\/debitia.com\/es_do\/wp-json\/wp\/v2\/posts\/6134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/debitia.com\/es_do\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/debitia.com\/es_do\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/debitia.com\/es_do\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/debitia.com\/es_do\/wp-json\/wp\/v2\/comments?post=6134"}],"version-history":[{"count":0,"href":"https:\/\/debitia.com\/es_do\/wp-json\/wp\/v2\/posts\/6134\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/debitia.com\/es_do\/wp-json\/wp\/v2\/media\/6137"}],"wp:attachment":[{"href":"https:\/\/debitia.com\/es_do\/wp-json\/wp\/v2\/media?parent=6134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/debitia.com\/es_do\/wp-json\/wp\/v2\/categories?post=6134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/debitia.com\/es_do\/wp-json\/wp\/v2\/tags?post=6134"},{"taxonomy":"post_series","embeddable":true,"href":"https:\/\/debitia.com\/es_do\/wp-json\/wp\/v2\/post_series?post=6134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}