{"id":593,"date":"2018-09-14T16:58:54","date_gmt":"2018-09-14T19:58:54","guid":{"rendered":"http:\/\/debitia.com.ar\/?p=593"},"modified":"2024-05-26T12:17:41","modified_gmt":"2024-05-26T15:17:41","slug":"gestion-de-cobranza-debita","status":"publish","type":"post","link":"https:\/\/debitia.com\/es_co\/gestion-de-cobranza-debita\/","title":{"rendered":"&#8220;La plataforma de Debitia Simplific\u00f3 nuestra Gesti\u00f3n y la hizo m\u00e1s m\u00e1s Rentable\u201d"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/debitia.com\/es_co\/gestion-de-cobranza-debita\/#OPTIMIZAR_LA_GESTION_DE_COBRANZA_Y_HACERLA_EFECTIVA\" >OPTIMIZAR LA GESTI\u00d3N DE COBRANZA Y HACERLA EFECTIVA<\/a><ul class='ez-toc-list-level-2' ><li class='ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/debitia.com\/es_co\/gestion-de-cobranza-debita\/#%C2%BFCual_es_el_objetivo_de_Debitia\" >\u00bfCu\u00e1l es el objetivo de Debitia?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/debitia.com\/es_co\/gestion-de-cobranza-debita\/#%C2%BFY_como_lo_logran\" >\u00bfY c\u00f3mo lo logran?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/debitia.com\/es_co\/gestion-de-cobranza-debita\/#%C2%BFPor_que_se_inclinaron_por_Debitia\" >\u00bfPor qu\u00e9 se inclinaron por Debitia?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/debitia.com\/es_co\/gestion-de-cobranza-debita\/#%C2%BFQue_mejoras_experimentaron_gracias_a_esta_nueva_metodologia_de_gestion_de_cobranza\" >\u00bfQu\u00e9 mejoras experimentaron gracias a esta nueva metodolog\u00eda de gesti\u00f3n de cobranza?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/debitia.com\/es_co\/gestion-de-cobranza-debita\/#%C2%BFCuanto_tiempo_demoro_la_implementacion\" >\u00bfCu\u00e1nto tiempo demor\u00f3 la implementaci\u00f3n?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/debitia.com\/es_co\/gestion-de-cobranza-debita\/#%C2%BFQue_aprendizaje_adquirieron_durante_esta_colaboracion\" >\u00bfQu\u00e9 aprendizaje adquirieron durante esta colaboraci\u00f3n?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/debitia.com\/es_co\/gestion-de-cobranza-debita\/#Optimizar_la_Gestion_de_Cobranzas\" >Optimizar la Gesti\u00f3n de Cobranzas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/debitia.com\/es_co\/gestion-de-cobranza-debita\/#La_propuesta_de_Debitia_es_ayudarlo_en_la_Gestion_de_Cobranza_reducir_costo_y_tiempo\" >La propuesta de Debitia es ayudarlo en la Gesti\u00f3n de Cobranza, reducir costo y tiempo.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/debitia.com\/es_co\/gestion-de-cobranza-debita\/#%C2%BFPorque_es_importante_sistematizar_la_de_Gestion_de_Cobranza\" >\u00bfPorque es importante sistematizar la de Gesti\u00f3n de Cobranza?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/debitia.com\/es_co\/gestion-de-cobranza-debita\/#Tiene_consultas_queremos_saber_en_que_podemos_ayudarloa\" >Tiene consultas, queremos saber en que podemos ayudarlo\/a<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h1 style=\"text-align: left;\"><span class=\"ez-toc-section\" id=\"OPTIMIZAR_LA_GESTION_DE_COBRANZA_Y_HACERLA_EFECTIVA\"><\/span><span style=\"font-size: 18px;\">OPTIMIZAR LA GESTI\u00d3N DE COBRANZA Y HACERLA EFECTIVA<br \/>\n<\/span><span class=\"ez-toc-section-end\"><\/span><\/h1>\n<figure id=\"attachment_594\" aria-describedby=\"caption-attachment-594\" style=\"width: 680px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-594 size-full\" title=\"OPTIMIZAR LA GESTI\u00d3N DE COBRANZAS\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2018\/04\/tarjeta-plata.jpg\" alt=\"Caso de \u00e9xitio &quot;optimizar la gesti\u00f3n de cobranzas&quot;\" width=\"680\" height=\"398\" srcset=\"https:\/\/debitia.com\/wp-content\/uploads\/2018\/04\/tarjeta-plata.jpg 680w, https:\/\/debitia.com\/wp-content\/uploads\/2018\/04\/tarjeta-plata-300x176.jpg 300w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><figcaption id=\"caption-attachment-594\" class=\"wp-caption-text\">Caso de \u00e9xitio &#8220;optimizar la gesti\u00f3n de cobranza&#8221;<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><em>Por Elsa Basile &#8211; La democratizaci\u00f3n en la gesti\u00f3n de cobranza es un novedoso concepto que funciona como punta de lanza en <a href=\"http:\/\/debitia.com.ar\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Debitia<\/strong><\/a>, una plataforma que busca poner al alcance de todas las empresas la transformaci\u00f3n digital en la Gesti\u00f3n de Cobranzas. <strong>Germ\u00e1n Morilla<\/strong>, Co-Fundador de la compa\u00f1\u00eda, y\u00a0<strong>Romina Franze<\/strong>, Gerente de Cobranzas de Tarjeta Plata (uno de sus grandes clientes), detallaron, cada uno desde su punto de vista, las virtudes del modelo para optimizar la gesti\u00f3n de cobranza y hacerla efectiva, que catapultaron un notable caso de \u00e9xito, de forma de hacer efectiva la Gesti\u00f3n de Cobranza.<br \/>\n<\/em><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFCual_es_el_objetivo_de_Debitia\"><\/span><span style=\"font-size: 18px;\"><strong>\u00bfCu\u00e1l es el objetivo de Debitia?<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\"><strong>Germ\u00e1n Morilla:<\/strong> -Nuestro enfoque es entender qu\u00e9 es lo que hace el cliente y c\u00f3mo podemos ayudar a mejorarlo. En los procesos, las automatizaciones, la medici\u00f3n de las gestiones, en qu\u00e9 cosas se pueden reducir costos, y les hacemos sugerencias de buenas pr\u00e1cticas. Apuntamos a dar una herramienta poderosa para optimizar la Gesti\u00f3n de Cobranza, que haga efectivo el proceso y que\u00a0 usuario sepa y pueda usarla.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFY_como_lo_logran\"><\/span><span style=\"font-size: 18px;\"><strong>\u00bfY c\u00f3mo lo logran?<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\"><strong>GM:<\/strong> -Antes de Debitia estuvimos 3 a\u00f1os trabajando con una empresa de USA, en Miami. Lo que hicimos fue desarrollar una aplicaci\u00f3n, un coraz\u00f3n de negocios, que puede resolver distintas industrias. Eso no quita que nos adaptamos a las necesidades del cliente y los requerimientos tecnol\u00f3gicos de la industria para optimizar la gesti\u00f3n de cobranzas y hacerla efectiva.<\/p>\n<p style=\"text-align: justify;\">Lo que hay por debajo de esto es un workflow muy potente, una interfaz de manejo de datos que permite procesar informaci\u00f3n en muy poco tiempo. Por caso, Tarjeta Plata carga unos 300 mil registros en pocos minutos diariamente. Inclusive el sistema podr\u00eda estar online comunic\u00e1ndose con un core de negocios actualizando datos en tiempo real.<\/p>\n<p style=\"text-align: justify;\"><strong>Romina, \u00bfqu\u00e9 necesitaba Tarjeta Plata cuando salieron a buscar un nuevo m\u00e9todo de gesti\u00f3n de cobranza?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Romina Franze<\/strong>: -La eficiencia plena en la gesti\u00f3n. Y contar con la inteligencia previa a que el operador reciba el dato. Nutrir un sistema que nos permita decir que bajo ciertas reglas nosotros podemos trabajar de determinada manera, y que esa inteligencia est\u00e9 mapeada en un flujo de procesos espec\u00edfico.<\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%C2%BFPor_que_se_inclinaron_por_Debitia\"><\/span><span style=\"font-size: 18px;\"><strong>\u00bfPor qu\u00e9 se inclinaron por Debitia?<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\"><strong>RF:<\/strong>\u00a0-Hubo 2 motivos principales: 1- La flexibilidad, que sea usuario, que no haya que involucrar a alguien de sistema; 2- El soporte. Otros nos daban apenas algunas horas y a m\u00ed no me sirve. El call trabaja de 8 a 22, entonces no puede faltar.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFQue_mejoras_experimentaron_gracias_a_esta_nueva_metodologia_de_gestion_de_cobranza\"><\/span><span style=\"font-size: 18px;\"><strong>\u00bfQu\u00e9 mejoras experimentaron gracias a esta nueva metodolog\u00eda de gesti\u00f3n de cobranza?<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\"><strong>RF:<\/strong> -Nosotros ten\u00edamos una unidad dentro del core que era de cobranza, en la cual depend\u00edamos del sistema. La cobranza es tan din\u00e1mica que es imposible hacer un pedido y esperar las horas desarrollador de nuestro departamento de sistemas, el cambio de pol\u00edtica o de mi estrategia no puede esperar 4 horas.<\/p>\n<p style=\"text-align: justify;\">Entonces esta nueva libertad que nosotros manejamos es una de las cosas m\u00e1s fundamentales. Y adem\u00e1s antes ten\u00edamos restricciones del sistema, por ejemplo, no nos conven\u00eda hacer una campa\u00f1a s\u00f3lo por 10 casos. Ahora la hacemos, no tenemos problema.<\/p>\n<p style=\"text-align: justify;\">Ya hace 9 meses que estamos trabajando juntos, y ellos nos siguen el ritmo, nos acompa\u00f1an muy de cerca y nos responden con mucha velocidad.<\/p>\n<p style=\"text-align: justify;\"><strong>GM:<\/strong>\u00a0-En Debitia damos soporte 24\/7. Es que, en realidad, generalmente no tenemos incidentes. En definitiva, nosotros entendemos que el cliente tiene que resolver algo y lo ayudamos a resolverlo. Es soporte en el uso de la aplicaci\u00f3n, no soporte t\u00e9cnico del que nos encargamos 100% nosotros.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFCuanto_tiempo_demoro_la_implementacion\"><\/span><span style=\"font-size: 18px;\"><strong>\u00bfCu\u00e1nto tiempo demor\u00f3 la implementaci\u00f3n?<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\"><strong>GM<\/strong>: -Al ser una cuenta cloud, en el caso de Tarjeta Plata estuvimos ajustando bastante el ingreso de datos, pero podemos tomar nada m\u00e1s que 3 semanas de puesta en marcha. Si el origen de datos est\u00e1 claro, son 3 semanas para ingresar esos datos, analizar c\u00f3mo ser\u00eda la estrategia de barrido, la interacci\u00f3n con el discador digital si lo hubiera, la capacitaci\u00f3n a los operadores, y listo.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFQue_aprendizaje_adquirieron_durante_esta_colaboracion\"><\/span><span style=\"font-size: 18px;\"><strong>\u00bfQu\u00e9 aprendizaje adquirieron durante esta colaboraci\u00f3n?<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\"><strong>RF:<\/strong> -Ven\u00edamos con una gesti\u00f3n de cobranza muy dura, respetando la estrategia a rajatabla. El proceso de aprendizaje es entender que podemos hacer lo que queremos, en el momento que queremos, en tiempo real. Aprendimos a tomar decisiones de manera m\u00e1s flexible e inmediatas. Como les pasamos toda la informaci\u00f3n, les damos todas las novedades de todos los clientes todos los d\u00edas, nunca tenemos desactualizado nuestro sistema. Somos mucho m\u00e1s productivos a menor costo.<\/p>\n<p style=\"text-align: justify;\">Si antes llam\u00e1bamos a 100 cuentas ahora llamamos a 80 porque sabemos que las otras 20 no hacen falta.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Optimizar_la_Gestion_de_Cobranzas\"><\/span><strong><span style=\"font-size: 18px;\">Optimizar la Gesti\u00f3n de Cobranzas<\/span><br \/>\n<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\"><strong>GM<\/strong>: -Ahora estamos implementando un <a href=\"https:\/\/debitia.com.ar\/machine-learning-en-la-gestion-de-cobranzas-machine-learning\/\">m\u00f3dulo de machine learning<\/a> que analiza el comportamiento de pago del cliente hacia atr\u00e1s, y eso permite realizar mejor la Gesti\u00f3n de Cobranzas porque ahorra recursos. Somos un \u00e1rea de sistemas externos, no tenemos limitantes t\u00e9cnicas. El sistema es seguro, porque est\u00e1 en Amazon, y tiene la alta disponibilidad que ellos ofrecen. Tiene la potencialidad y flexibilidad de hacer lo que el cliente necesite.<\/p>\n<p style=\"text-align: justify;\"><em>Fuente:\u00a0<a href=\"http:\/\/ccncobranzas.com\/interview\/377-rftp\" target=\"_blank\" rel=\"noopener\">CCN Cr\u00e9ditos y cobranzas<\/a><\/em><\/p>\n<hr \/>\n<h2 class=\"entry-content\"><span class=\"ez-toc-section\" id=\"La_propuesta_de_Debitia_es_ayudarlo_en_la_Gestion_de_Cobranza_reducir_costo_y_tiempo\"><\/span><strong><span style=\"font-size: 18px;\">La propuesta de Debitia es ayudarlo en la Gesti\u00f3n de Cobranza, reducir costo y tiempo.<\/span><br \/>\n<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li>Poder <strong>automatizar la Gesti\u00f3n sus Cobranza<\/strong> desde la emisi\u00f3n de la factura o deuda hasta su cobro, mediante un\u00a0 de sistema que permita <strong>mapear su Pol\u00edtica de Cobranza,<\/strong> el <strong>seguimiento de los pagos<\/strong> y contacto con sus clientes.<\/li>\n<li>Que su empresa disponga de l\u00edmites y cursos de acci\u00f3n pre establecidos y automatizados.<\/li>\n<li>Poder<strong> organizar las tareas\u00a0<\/strong> y los <strong>recurso<\/strong>s para mantener la <strong>calidad de sus carteras, mediante un proceso <em>predecible, medible y controlable,<\/em><\/strong> que registre las gestiones que usted realiza con sus clientes.<\/li>\n<li>Ayudarlo a que pueda <strong>organizar su cartera<\/strong> de morosos seg\u00fan la complejidad de cobro, basado en la<strong> iteraci\u00f3n y respuestas<\/strong> que obtenga de sus clientes y al <strong>cumplimiento de las promesas<\/strong> de parte de ellos.<\/li>\n<li>Poder <strong>interactuar<\/strong> con sus clientes en los<strong> distintos canales<\/strong> de contacto digitales integrados y <strong>automatizados<\/strong> de Debitia.<\/li>\n<li>Ayudarlo a organizar la <strong>pr\u00f3xima y mejor acci\u00f3n<\/strong> sobre cada uno de sus clientes a fin de lograr el pago.<\/li>\n<li>Organizar la planificaci\u00f3n y el orden en que ser\u00e1n contactados los clientes y la forma de <a href=\"https:\/\/debitia.com.ar\/proceso-de-cobranza-eficiente\/\">priorizar<\/a> seg\u00fan criterios relevantes para la empresa.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFPorque_es_importante_sistematizar_la_de_Gestion_de_Cobranza\"><\/span><span style=\"font-size: 18px;\">\u00bfPorque es importante <em>sistematizar<\/em> la de Gesti\u00f3n de Cobranza?<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Estamos convencidos que mediante un <em><strong>PROCESO<\/strong><\/em><\/p>\n<ul>\n<li><em><strong> organizado<\/strong><\/em><\/li>\n<li>que utilice <strong><em>buenas pr\u00e1cticas<\/em><\/strong> y<\/li>\n<li>tenga <strong><em>soporte tecnol\u00f3gico<\/em> <\/strong>adecuado,<\/li>\n<li>permitir\u00e1 <strong><em>potenciar a su equipo<\/em><\/strong> que gestionan la\u00a0 cobranza.<\/li>\n<\/ul>\n<figure id=\"attachment_965\" aria-describedby=\"caption-attachment-965\" style=\"width: 1001px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-965\" title=\"OPTIMIZAR LA GESTI\u00d3N DE COBRANZAS\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2018\/10\/4-que-de-debitia.png\" sizes=\"auto, (max-width: 886px) 100vw, 886px\" srcset=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2018\/10\/4-que-de-debitia.png 886w, https:\/\/debitia.com.ar\/wp-content\/uploads\/2018\/10\/4-que-de-debitia-300x157.png 300w, https:\/\/debitia.com.ar\/wp-content\/uploads\/2018\/10\/4-que-de-debitia-768x403.png 768w\" alt=\"OPTIMIZAR LA GESTI\u00d3N DE COBRANZAS\" width=\"1001\" height=\"525\" \/><figcaption id=\"caption-attachment-965\" class=\"wp-caption-text\">OPTIMIZAR LA GESTI\u00d3N DE COBRANZA<\/figcaption><\/figure>\n<p><strong>Ese es el desaf\u00edo de Debitia y ya lo hemos resuelto en diferentes clientes de diferentes industrias.<br \/>\n<\/strong><\/p>\n<p><b>\u00a0La \u00abarticulaci\u00f3n de <\/b><b>las Mejores Practicas\u00bb\u00a0<\/b>en la\u00a0<b>Gesti\u00f3n\u00a0<\/b><b>de C<\/b><b>obranza <\/b>y la <strong>disponibilidad para las empresas en forma online.<\/strong><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Tiene_consultas_queremos_saber_en_que_podemos_ayudarloa\"><\/span><span style=\"font-size: 18px;\">Tiene consultas, queremos saber en que podemos ayudarlo\/a<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<figure id=\"attachment_1328\" aria-describedby=\"caption-attachment-1328\" style=\"width: 476px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/api.whatsapp.com\/send?phone=5491141891939&amp;text=Quiero%20recibir%20m\u00e1s%20informaci\u00f3n%20sobre%20Debitia%20gracias!%20Mi%20nombre%20es\u2026%20\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1328\" title=\"OPTIMIZAR LA GESTI\u00d3N DE COBRANZAS\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2019\/02\/Pongase-en-contacto-con-German-Morilla.png\" alt=\"OPTIMIZAR LA GESTI\u00d3N DE COBRANZAS\" width=\"476\" height=\"214\" srcset=\"https:\/\/debitia.com\/wp-content\/uploads\/2019\/02\/Pongase-en-contacto-con-German-Morilla.png 885w, https:\/\/debitia.com\/wp-content\/uploads\/2019\/02\/Pongase-en-contacto-con-German-Morilla-300x135.png 300w, https:\/\/debitia.com\/wp-content\/uploads\/2019\/02\/Pongase-en-contacto-con-German-Morilla-768x345.png 768w\" sizes=\"auto, (max-width: 476px) 100vw, 476px\" \/><\/a><figcaption id=\"caption-attachment-1328\" class=\"wp-caption-text\">OPTIMIZAR LA GESTI\u00d3N DE COBRANZAS<\/figcaption><\/figure>\n<p><span class=\"white-text\" style=\"font-size: 9px; color: #ffffff;\">Gesti\u00f3n de cobranza <span class=\"white-text\">de facturas impagas.<\/span> optimizaci\u00f3n en la Gesti\u00f3n de Cobranza.<br \/>\n<\/span><\/p>\n<p><span class=\"white-text\" style=\"font-size: 9px; color: #ffffff;\">Optimizar la gesti\u00f3n de cobranza. Disponer de un proceso de Gesti\u00f3n de Cobranza efectivo o efectiva. El poder implementar <span class=\"white-text\">un proceso de Gesti\u00f3n de Cobranzas efectivo o efectiva.<\/span><br \/>\n<\/span><\/p>\n<p><span class=\"white-text\" style=\"font-size: 21px;\"><span style=\"font-size: 9px; color: #ffffff;\">Debemos optimizar la gesti\u00f3n de cobranza mediante un Sistema de gesti\u00f3n de cobranza de facturas. optimizaci\u00f3n en la Gesti\u00f3n de Cobranzas<\/span><br \/>\n<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>OPTIMIZAR LA GESTI\u00d3N DE COBRANZA Y HACERLA EFECTIVA Por Elsa Basile &#8211; La democratizaci\u00f3n en la gesti\u00f3n de cobranza es un novedoso concepto que funciona como punta de lanza en Debitia, una plataforma que busca poner al alcance de todas las empresas la transformaci\u00f3n digital en la Gesti\u00f3n de Cobranzas. Germ\u00e1n Morilla, Co-Fundador de la&hellip;<\/p>","protected":false},"author":5,"featured_media":594,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[14,10,11],"post_series":[],"class_list":["post-593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-debitia-gestion-de-cobranzas","tag-gestion-de-cobranzas","tag-sistema-de-gestion-de-cobranzas","entry","has-media"],"_links":{"self":[{"href":"https:\/\/debitia.com\/es_co\/wp-json\/wp\/v2\/posts\/593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/debitia.com\/es_co\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/debitia.com\/es_co\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/debitia.com\/es_co\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/debitia.com\/es_co\/wp-json\/wp\/v2\/comments?post=593"}],"version-history":[{"count":0,"href":"https:\/\/debitia.com\/es_co\/wp-json\/wp\/v2\/posts\/593\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/debitia.com\/es_co\/wp-json\/wp\/v2\/media\/594"}],"wp:attachment":[{"href":"https:\/\/debitia.com\/es_co\/wp-json\/wp\/v2\/media?parent=593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/debitia.com\/es_co\/wp-json\/wp\/v2\/categories?post=593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/debitia.com\/es_co\/wp-json\/wp\/v2\/tags?post=593"},{"taxonomy":"post_series","embeddable":true,"href":"https:\/\/debitia.com\/es_co\/wp-json\/wp\/v2\/post_series?post=593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}