{"id":694,"date":"2018-09-13T14:50:42","date_gmt":"2018-09-13T17:50:42","guid":{"rendered":"https:\/\/debitia.com.ar\/?p=694"},"modified":"2024-05-26T12:19:30","modified_gmt":"2024-05-26T15:19:30","slug":"machine-learning-en-cobranzas","status":"publish","type":"post","link":"https:\/\/debitia.com\/es_cl\/machine-learning-en-cobranzas\/","title":{"rendered":"El Machine Learning en la Gesti\u00f3n de Cobranzas , Debitia"},"content":{"rendered":"<figure id=\"attachment_696\" aria-describedby=\"caption-attachment-696\" style=\"width: 1280px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-696 size-full\" title=\"Gesti\u00f3n de Cobranzas con Machine Learning\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2018\/09\/machinelearning.jpg\" alt=\"Gesti\u00f3n de Cobranzas con Machine Learning\" width=\"1280\" height=\"720\" srcset=\"https:\/\/debitia.com\/wp-content\/uploads\/2018\/09\/machinelearning.jpg 1280w, https:\/\/debitia.com\/wp-content\/uploads\/2018\/09\/machinelearning-300x169.jpg 300w, https:\/\/debitia.com\/wp-content\/uploads\/2018\/09\/machinelearning-768x432.jpg 768w, https:\/\/debitia.com\/wp-content\/uploads\/2018\/09\/machinelearning-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><figcaption id=\"caption-attachment-696\" class=\"wp-caption-text\">Gestion de Cobranzas con Machine Learning, ahorra costos, tiempos y recursos.<\/figcaption><\/figure>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/debitia.com\/es_cl\/machine-learning-en-cobranzas\/#Gestion_de_Cobranzas_con_Machine_Learning\" >Gesti\u00f3n de Cobranzas con Machine Learning<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/debitia.com\/es_cl\/machine-learning-en-cobranzas\/#Modelado\" >Modelado<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/debitia.com\/es_cl\/machine-learning-en-cobranzas\/#Probabilidades_de_pagos\" >Probabilidades de pagos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/debitia.com\/es_cl\/machine-learning-en-cobranzas\/#Beneficios\" >Beneficios:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/debitia.com\/es_cl\/machine-learning-en-cobranzas\/#El_Machine_Learning_en_la_Gestion_de_Cobranzas_es_tambien_es_parte_de_la_Transformacion_Digital\" >El Machine Learning en la Gesti\u00f3n de Cobranzas es tambi\u00e9n, es parte de la Transformaci\u00f3n Digital<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/debitia.com\/es_cl\/machine-learning-en-cobranzas\/#Tiene_consultas_queremos_saber_en_que_podemos_ayudarloa\" >Tiene consultas, queremos saber en que podemos ayudarlo\/a<\/a><\/li><\/ul><\/nav><\/div>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"Gestion_de_Cobranzas_con_Machine_Learning\"><\/span>Gesti\u00f3n de Cobranzas con Machine Learning<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">Es utilizar algoritmos que aprendan a encontrar patrones y soluciones en la informaci\u00f3n diaria para ahorrar costos y maximizar la Gesti\u00f3n. Gestion de Cobranzas con Machine Learning<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li style=\"text-align: justify;\">Disponibilizarlo en un sistema de Gesti\u00f3n de Cobranzas ayudara a gestionar eficientemente<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li style=\"text-align: justify;\">El proceso de cobranzas se basa en la utilizaci\u00f3n de recursos limitados: sistemas,\u00a0herramientas masivas de contactaci\u00f3n (Mail, SMS) o mediante gestores que realizan llamadas.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li style=\"text-align: justify;\">La curva de recupero es lineal, solo cobro m\u00e1s agregando recursos, pero de todas formas es una funci\u00f3n asint\u00f3nica decreciente.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li style=\"text-align: justify;\">Hay clientes que por mas que re contacte en forma masiva o por gesti\u00f3n personal, no los lograre cobrar.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li style=\"text-align: justify;\">Si imaginamos un Contact Center de Cobranzas con 15 gestores, que realizan un total de 2,000 llamadas diarias, podr\u00edamos aumentar la eficiencia.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li style=\"text-align: justify;\">No solo realizando una buena estrategia de barrido, basada en una metodolog\u00eda de Gesti\u00f3n de Cobranzas, como la que vemos abajo.<\/li>\n<\/ul>\n<div class=\"slate-resizable-image-embed slate-image-embed__resize-full-width\" style=\"text-align: justify;\" data-image-href=\"http:\/\/debitia.com\/2016\/09\/18\/proceso-de-gestion-de-cobranzas\/\">\n<figure id=\"attachment_695\" aria-describedby=\"caption-attachment-695\" style=\"width: 1346px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-695\" title=\"Gesti\u00f3n de Cobranzas con Machine Learning\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2018\/09\/workflow-cobranzas.jpg\" alt=\"Gesti\u00f3n de Cobranzas con Machine Learning\" width=\"1346\" height=\"708\" \/><figcaption id=\"caption-attachment-695\" class=\"wp-caption-text\">Gesti\u00f3n de Cobranzas con Machine Learning<\/figcaption><\/figure>\n<\/div>\n<p style=\"text-align: justify;\">Tambi\u00e9n ser\u00e1 necesario potenciarlo mediante un elemento que permita planificar los llamados discriminando a los deudores en base a un umbral determinado por su <strong>&#8220;Probabilidad de Pago&#8221;.<\/strong><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Modelado\"><\/span><span style=\"font-size: 18px;\">Modelado<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li style=\"text-align: justify;\">De forma de utilizar los recursos (<em>Gestores, Acciones masivas, Sistema y Estrategia<\/em>) de forma mucho m\u00e1s eficiente.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li style=\"text-align: justify;\">Se logra mediante la utilizaci\u00f3n de un \u201c<strong>Scoring\u00a0de Cobranzas<\/strong>\u201d que proporciona una valoraci\u00f3n cuantitativa del potencial de recuperaci\u00f3n de un deudor<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li style=\"text-align: justify;\">que \u201cajusta\u201d u \u201cordena\u201d los casos a contactar bas\u00e1ndonos en esa probabilidad.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li style=\"text-align: justify;\">Define la probabilidad de recuperaci\u00f3n y el tramo de la gesti\u00f3n en que es m\u00e1s probable recuperar<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li style=\"text-align: justify;\">Permite generar un modelo consistente y con buen poder predictivo.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li style=\"text-align: justify;\">El Proceso de Scoring de cobranzas toma variables medibles que recolecta de la historia de los clientes en mora .<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li style=\"text-align: justify;\">Ejecuta con cierta frecuencia peri\u00f3dica un modelo estad\u00edstico de correlaci\u00f3n de dichas variables.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li style=\"text-align: justify;\">El modelo calcula la probabilidad de pago asociado a cada valor de las variables.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2957\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2018\/09\/Machine-learning.png\" alt=\"\" width=\"886\" height=\"371\" srcset=\"https:\/\/debitia.com\/wp-content\/uploads\/2018\/09\/Machine-learning.png 886w, https:\/\/debitia.com\/wp-content\/uploads\/2018\/09\/Machine-learning-300x126.png 300w, https:\/\/debitia.com\/wp-content\/uploads\/2018\/09\/Machine-learning-768x322.png 768w\" sizes=\"auto, (max-width: 886px) 100vw, 886px\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Probabilidades_de_pagos\"><\/span><span style=\"font-size: 18px;\">Probabilidades de pagos<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">Esas variables est\u00e1n relacionadas:<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li style=\"text-align: justify;\">Al <strong>perfil de la operaci\u00f3n financiera<\/strong><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li style=\"text-align: justify;\"><strong>al perfil del cliente<\/strong><em><br \/>\n<\/em><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li style=\"text-align: justify;\"><strong>a su comportamiento de pagos<\/strong><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li style=\"text-align: justify;\"><strong>otras variables<\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Por ejemplo, que para una determinada provincia, producto o tipo de cliente\u00a0existe una mayor probabilidad de recupero para un cierto plazo.<\/p>\n<p style=\"text-align: justify;\"><strong>El modelo estad\u00edstico \u201cata las correlaciones\u201d entre todas las variables y calcula los pesos espec\u00edficos de cada una en el modelo<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Por esto cada producto financiero o\u00a0plazo dentro de la cartera tendr\u00e1 un diferente Scoring.<\/p>\n<blockquote><p>Utilizando este Scoring\u00a0y ajustando la estrategia de contactaci\u00f3n del d\u00eda a d\u00eda, es como podemos optimizar la gesti\u00f3n<\/p>\n<ul>\n<li>En base a un umbral<\/li>\n<li>Que permita la utilizaci\u00f3n de los recursos en forma eficiente.<\/li>\n<li>De<strong>jando de llamar a los deudores que seg\u00fan mi modelo deber\u00edan pagar en forma voluntaria sin intervenci\u00f3n de los gestores.<\/strong><\/li>\n<\/ul>\n<\/blockquote>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"Beneficios\"><\/span><span style=\"font-size: 18px;\">Beneficios:<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">El Machine Learning en la Gesti\u00f3n de Cobranzas es utilizar algoritmos que aprendan a encontrar patrones y soluciones en la informaci\u00f3n diaria para ahorrar costos y maximizar la Gesti\u00f3n.<\/p>\n<p style=\"text-align: justify;\">El Proceso de Scoring de cobranzas toma variables medibles que recolecta de la historia de los clientes en mora y ejecuta con cierta frecuencia peri\u00f3dica un modelo estad\u00edstico<br \/>\nde correlaci\u00f3n de dichas variables. El modelo calcula la probabilidad de pago asociado a cada valor de las variables.<\/p>\n<p style=\"text-align: justify;\">Utilizando este Scoring y ajustando la estrategia de contactaci\u00f3n del d\u00eda a d\u00eda, es como podemos optimizar la gesti\u00f3n en base a un umbral que permita la utilizaci\u00f3n de los recursos en forma eficiente, dejando de llamar a los deudores que seg\u00fan mi modelo deber\u00edan pagar en forma voluntaria sin intervenci\u00f3n de los gestores.<\/p>\n<p style=\"text-align: justify;\">Para un Contact Center con 15 gestores, que realizan 2,000 llamadas diarias, podr\u00edamos aumentar la eficiencia, mediante un Scoring que permita planificar los llamados discriminando a los deudores en base a un umbral determinado por su \u201cProbabilidad de Pago\u201d.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"El_Machine_Learning_en_la_Gestion_de_Cobranzas_es_tambien_es_parte_de_la_Transformacion_Digital\"><\/span><span style=\"font-size: 18px;\"><strong>El Machine Learning en la Gesti\u00f3n de Cobranzas es tambi\u00e9n<\/strong>, es parte de la Transformaci\u00f3n Digital<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\"><strong>El Machine Learning en la Gesti\u00f3n de Cobranzas, <\/strong><strong>es una realidad, disponer de estas herramientas integradas en la elaboraci\u00f3n de la estrategia de barrido diaria es una necesidad.\u00a0<\/strong><\/p>\n<p><span style=\"font-size: 18px; color: #ff0000;\"><strong>La propuesta de Debitia, es ayudarlo en la Gesti\u00f3n de Cobranzas<\/strong><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2515 size-full\" title=\"SISTEMA DE COBRANZAS\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2018\/09\/La-propuesta-de-Debitia.png\" alt=\"SISTEMA DE COBRANZAS\" width=\"886\" height=\"471\" srcset=\"https:\/\/debitia.com\/wp-content\/uploads\/2018\/09\/La-propuesta-de-Debitia.png 886w, https:\/\/debitia.com\/wp-content\/uploads\/2018\/09\/La-propuesta-de-Debitia-300x159.png 300w, https:\/\/debitia.com\/wp-content\/uploads\/2018\/09\/La-propuesta-de-Debitia-768x408.png 768w\" sizes=\"auto, (max-width: 886px) 100vw, 886px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2495\" title=\"Gestion de Cobranzas con Machine Learning\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-pro-uselo-ya-mismo.jpg\" alt=\"\" width=\"196\" height=\"144\" \/> \u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2494\" title=\"Gestion de Cobranzas con Machine Learning\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-pro-estrategia-y-coordinacion.jpg\" alt=\"\" width=\"195\" height=\"143\" \/> \u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2490\" title=\"Gestion de Cobranzas con Machine Learning\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-pro-simplifica-el-trabajo-1.jpg\" alt=\"\" width=\"187\" height=\"148\" srcset=\"https:\/\/debitia.com\/wp-content\/uploads\/2020\/04\/debitia-pro-simplifica-el-trabajo-1.jpg 380w, https:\/\/debitia.com\/wp-content\/uploads\/2020\/04\/debitia-pro-simplifica-el-trabajo-1-300x237.jpg 300w\" sizes=\"auto, (max-width: 187px) 100vw, 187px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2572\" title=\"GESTION DE COBRANZAS\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-saber-lo-que-hace-el-equipo.png\" alt=\"\" width=\"34\" height=\"34\" \/> \u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2571\" title=\"GESTION DE COBRANZAS\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-reducir-el-plazo-de-cobro.png\" alt=\"\" width=\"32\" height=\"32\" \/> \u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2570\" title=\"GESTION DE COBRANZAS\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-prevenir-la-mora.png\" alt=\"\" width=\"31\" height=\"31\" \/> \u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2568\" title=\"GESTION DE COBRANZAS\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-clientes-importantes-primero.png\" alt=\"\" width=\"32\" height=\"32\" \/> \u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2567\" title=\"GESTION DE COBRANZAS\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-interactuar-con-el-cliente.png\" alt=\"\" width=\"33\" height=\"33\" \/> \u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2564\" title=\"GESTION DE COBRANZAS\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-organiza-clientes.png\" alt=\"\" width=\"32\" height=\"32\" \/> \u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2548\" title=\"GESTION DE COBRANZAS\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-beneficios-empieza-a-gestionar-ya.png\" alt=\"\" width=\"31\" height=\"31\" \/><\/p>\n<p style=\"text-align: justify;\">Nuestro software para gesti\u00f3n de cobranzas, es efectivo en coordinar y supervisar el conjunto de acciones, negociaciones y organizar la Gesti\u00f3n de Cobranza de su equipo de forma de recuperar la liquidez r\u00e1pidamente en sus activos.<\/p>\n<p><span style=\"font-size: 18px;\"><strong>NUESTRA PROPUESTA:<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><b><strong>Ayudarlo a utilizar las mejores pr\u00e1cticas y estrategias de Gesti\u00f3n de Cobranzas. Recuperar su dinero, coordinar y supervisar su equipo de trabajo, aun gestionando en forma remota.<\/strong><\/b><\/p>\n<p style=\"text-align: justify;\"><strong>Ya ayudamos a <span style=\"color: #ff0000;\">Empresas<\/span>, Empresas de <span style=\"color: #ff0000;\">telecomunicaciones<\/span>, <span style=\"color: #ff0000;\">Bancos<\/span>, Bancos <span style=\"color: #ff0000;\">Digitales<\/span> y <span style=\"color: #ff0000;\">Fintech<\/span> de Cr\u00e9dito en toda Am\u00e9rica Latina.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2474\" title=\"SISTEMA DE COBRANZAS\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2020\/04\/debitia-clientes.png\" alt=\"SISTEMA DE COBRANZAS\" width=\"831\" height=\"97\" srcset=\"https:\/\/debitia.com\/wp-content\/uploads\/2020\/04\/debitia-clientes.png 1200w, https:\/\/debitia.com\/wp-content\/uploads\/2020\/04\/debitia-clientes-300x35.png 300w, https:\/\/debitia.com\/wp-content\/uploads\/2020\/04\/debitia-clientes-1024x119.png 1024w, https:\/\/debitia.com\/wp-content\/uploads\/2020\/04\/debitia-clientes-768x90.png 768w\" sizes=\"auto, (max-width: 831px) 100vw, 831px\" \/><\/p>\n<p><a href=\"https:\/\/debitia.com.ar\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2799 size-full\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2019\/01\/Pagina-princial.png\" alt=\"\" width=\"886\" height=\"502\" srcset=\"https:\/\/debitia.com\/wp-content\/uploads\/2019\/01\/Pagina-princial.png 886w, https:\/\/debitia.com\/wp-content\/uploads\/2019\/01\/Pagina-princial-300x170.png 300w, https:\/\/debitia.com\/wp-content\/uploads\/2019\/01\/Pagina-princial-768x435.png 768w\" sizes=\"auto, (max-width: 886px) 100vw, 886px\" \/><\/a><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Tiene_consultas_queremos_saber_en_que_podemos_ayudarloa\"><\/span><span style=\"font-size: 18px;\">Tiene consultas, queremos saber en que podemos ayudarlo\/a<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><a href=\"https:\/\/api.whatsapp.com\/send?phone=5491141891939&amp;text=Quiero%20recibir%20m\u00e1s%20informaci\u00f3n%20sobre%20Debitia%20gracias!%20Mi%20nombre%20es\u2026%20\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-818\" src=\"https:\/\/debitia.com.ar\/wp-content\/uploads\/2018\/09\/Pongase-en-contacto-con-German-Morilla.png\" alt=\"\" width=\"395\" height=\"178\" srcset=\"https:\/\/debitia.com\/wp-content\/uploads\/2018\/09\/Pongase-en-contacto-con-German-Morilla.png 885w, https:\/\/debitia.com\/wp-content\/uploads\/2018\/09\/Pongase-en-contacto-con-German-Morilla-300x135.png 300w, https:\/\/debitia.com\/wp-content\/uploads\/2018\/09\/Pongase-en-contacto-con-German-Morilla-768x345.png 768w\" sizes=\"auto, (max-width: 395px) 100vw, 395px\" \/><\/a><\/p>\n<p><span style=\"font-size: 21px;\">\u00a0<span style=\"font-size: 9px; color: #ffffff;\">Automatizacion cuentas por cobrar. Sistema de gestion de cobranzas. Gestion de cobranzas cobro recobro. Estapas de cobranzas cobro recobro. Software cobranzas Software para cobranzas Software para cobranzas. Gestion de Cobranzas con Machine Learning<\/span><br \/>\n<\/span><\/p>\n<p><span style=\"font-size: 9px; color: #ffffff;\">Usar Software para gestion de cobranzas B2B. Automatizacion cuentas por cobrar. Sistema de gestion de cobranzas. Gestion de cobranzas cobro recobro. Gestion de Cobranzas con Machine Learning . Software cobranzas sistema de cobranzas. Gestion como cobranzas software cobranzas. Gestion de Cobranzas con Machine Learning<\/span><span style=\"font-size: 18px; color: #333333;\"><br \/>\n<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Gesti\u00f3n de Cobranzas con Machine Learning Es utilizar algoritmos que aprendan a encontrar patrones y soluciones en la informaci\u00f3n diaria para ahorrar costos y maximizar la Gesti\u00f3n. Gestion de Cobranzas con Machine Learning Disponibilizarlo en un sistema de Gesti\u00f3n de Cobranzas ayudara a gestionar eficientemente El proceso de cobranzas se basa en la utilizaci\u00f3n de&hellip;<\/p>","protected":false},"author":5,"featured_media":696,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[12,11],"post_series":[],"class_list":["post-694","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-machine-learning-en-la-gestion-de-cobranzas","tag-sistema-de-gestion-de-cobranzas","entry","has-media"],"_links":{"self":[{"href":"https:\/\/debitia.com\/es_cl\/wp-json\/wp\/v2\/posts\/694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/debitia.com\/es_cl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/debitia.com\/es_cl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/debitia.com\/es_cl\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/debitia.com\/es_cl\/wp-json\/wp\/v2\/comments?post=694"}],"version-history":[{"count":0,"href":"https:\/\/debitia.com\/es_cl\/wp-json\/wp\/v2\/posts\/694\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/debitia.com\/es_cl\/wp-json\/wp\/v2\/media\/696"}],"wp:attachment":[{"href":"https:\/\/debitia.com\/es_cl\/wp-json\/wp\/v2\/media?parent=694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/debitia.com\/es_cl\/wp-json\/wp\/v2\/categories?post=694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/debitia.com\/es_cl\/wp-json\/wp\/v2\/tags?post=694"},{"taxonomy":"post_series","embeddable":true,"href":"https:\/\/debitia.com\/es_cl\/wp-json\/wp\/v2\/post_series?post=694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}